{"id":35811,"date":"2021-10-05T14:30:52","date_gmt":"2021-10-05T19:30:52","guid":{"rendered":"https:\/\/latamjournalismreview.org\/?p=35811"},"modified":"2021-12-17T12:13:43","modified_gmt":"2021-12-17T17:13:43","slug":"prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot","status":"publish","type":"post","link":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/","title":{"rendered":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot"},"content":{"rendered":"<p>La prensa debe hacer un mea culpa sobre su papel en la elecci\u00f3n de presidentes \u201cneofascistas\" como Jair Bolsonaro y Donald Trump, dice la periodista, escritora y documentalista brasile\u00f1a <a href=\"https:\/\/twitter.com\/brumelianebrum\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/twitter.com\/brumelianebrum\">Eliane Brum<\/a>, una de las ganadoras del Premio Maria Moors Cabot 2021.<\/p>\n<p>\u201cS\u00ed, existe el fen\u00f3meno de la posverdad, la autoverdad, las <em>fake news<\/em>, etc. Pero la prensa tambi\u00e9n ha perdido credibilidad ante la poblaci\u00f3n, debido a sus elecciones editoriales, comerciales y pol\u00edticas muy poco transparentes. Y porque, en varios pa\u00edses y tambi\u00e9n en Brasil, gran parte de la poblaci\u00f3n no se sinti\u00f3 representada por la cobertura de la prensa ni se reconoci\u00f3 en ella. Sin enfrentar estas contradicciones y responsabilidades, ser\u00e1 dif\u00edcil avanzar en un momento tan complejo y dif\u00edcil como el presente\u201d, dijo Brum en una entrevista con <strong>LatAm Journalism Review (LJR)<\/strong>.<\/p>\n<p>Seg\u00fan Brum, \u201clas fuerzas neofascistas\" aprovecharon esta crisis de credibilidad para debilitar a la prensa y la democracia. \u201cSolo pudieron crear esta industria de 'hechos alternativos' porque la crisis de credibilidad y representaci\u00f3n ya estaba ah\u00ed\", dijo.<\/p>\n<p>En la entrevista, Brum tambi\u00e9n habla sobre las veces que sufri\u00f3 acoso sexual y discriminaci\u00f3n en las redacciones brasile\u00f1as, sobre la experiencia de ser madre a los 15 a\u00f1os y la falta de apoyo en el trabajo, adem\u00e1s de la decisi\u00f3n de mudarse, en 2017, de S\u00e3o Paulo, la metr\u00f3polis brasile\u00f1a m\u00e1s grande, hasta Altamira, un municipio violento en el interior de la Amazon\u00eda.<\/p>\n<p>Los premios Cabot son otorgados por la Escuela de Periodismo de la Universidad de Columbia en Estados Unidos y \u201chonran a los periodistas y organizaciones de noticias por su excelencia profesional y cobertura del hemisferio occidental que promueve el entendimiento interamericano\u201d. Este a\u00f1o, por primera vez desde su fundaci\u00f3n en 1938, <a href=\"https:\/\/latamjournalismreview.org\/es\/articles\/todos-los-premios-cabot-se-otorgan-a-mujeres-periodistas-por-primera-vez-en-la-historia-del-premio-que-honra-reportajes-sobre-las-americas\/\" target=\"_blank\" rel=\"noopener\">todas las ganadoras son mujeres periodistas<\/a>. Recibir\u00e1n medallas de oro y un honorario de US $5.000. La ceremonia de premiaci\u00f3n ser\u00e1 el 12 de octubre.<\/p>\n<div id=\"attachment_35225\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-35225\" id=\"longdesc-return-35226\" class=\"wp-image-35227\" tabindex=\"-1\" src=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Eliane-Brum-Credito-Azul-Serra-300x200.jpg\" alt=\"A jornalista Eliane Brum\" width=\"800\" height=\"533\" longdesc=\"https:\/\/latamjournalismreview.org?longdesc=35226&amp;referrer=35228\" srcset=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Eliane-Brum-Credito-Azul-Serra-300x200.jpg 300w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Eliane-Brum-Credito-Azul-Serra-1024x683.jpg 1024w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Eliane-Brum-Credito-Azul-Serra-768x512.jpg 768w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Eliane-Brum-Credito-Azul-Serra-1536x1024.jpg 1536w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Eliane-Brum-Credito-Azul-Serra-2048x1365.jpg 2048w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Eliane-Brum-Credito-Azul-Serra-350x234.jpg 350w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-35225\" class=\"wp-caption-text\">Periodista brasile\u00f1a, escritora y documentalista, <a href=\"https:\/\/twitter.com\/brumelianebrum\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/twitter.com\/brumelianebrum\">Eliane Brum<\/a>, una de las ganadoras de los Premios Maria Moors Cabot 2021. (Foto: Azul Serra)<\/p><\/div>\n<p><strong>LatAm Journalism Review<\/strong>: <strong>Este a\u00f1o, todas las ganadoras del premio Cabot son mujeres. \u00bfQu\u00e9 desaf\u00edos enfrent\u00f3 como periodista que trabaja en Am\u00e9rica Latina y Brasil?<\/strong><\/p>\n<p><strong>Eliane Brum:<\/strong> El entorno de las redacciones sol\u00eda ser, y en muchos casos sigue siendo, muy sexista. El acoso sexual y moral hacia las mujeres se consideraba \u201cnormal\". Sufr\u00ed acoso sexual en diferentes momentos, por parte de hombres en cargos directivos, en los lugares donde trabajaba, pero reaccion\u00e9 con contundencia cada vez y no sufr\u00ed represalias por ello, como sucedi\u00f3 con otras colegas en otros contextos. Tambi\u00e9n sufr\u00ed acoso en el sentido de bromas sexistas, comentarios mis\u00f3ginos y \u201ccoqueteo\" y \u201cbromas\". Me di cuenta en los \u00faltimos a\u00f1os de que, en estos casos, yo misma hab\u00eda \u201cnormalizado\u201d lo anormal e inaceptable, viviendo con este tipo de acoso como si no fuera absurdo. En este sentido, agradezco mucho a la nueva generaci\u00f3n de feministas que llevaron adelante la lucha de sus madres, abuelas y bisabuelas, trazando una l\u00ednea y estableciendo l\u00edmites claros, en movimientos como \u201cPrimeiro Ass\u00e9dio\u201d, \u201cNi Una Menos\u201d y \u201cMe Too\u201d.<\/p>\n<p>Otra forma de acoso moral com\u00fan es, cuando reaccionas a lo inaceptable, ser etiquetada como \u201cloca\" o \u201cdemente\", siendo el blanco de comentarios como \u201cdebes estar en tu periodo\" o \u201cest\u00e1s mal comida\" [una forma vulgar de decir que \u201cnecesitas acostarte con alguien\"]. O de lo contrario, te llaman \u201cperra\" o \u201cputa\". Esto no solo ocurre dentro de las redacciones, sino tambi\u00e9n en el exterior. En 2011, un s\u00e1bado por la ma\u00f1ana, estaba hablando con mi esposo y mi hija en la sala de estar de mi casa cuando lleg\u00f3 un mensaje a trav\u00e9s de mi tel\u00e9fono celular. Un amigo me advirti\u00f3 que el pastor Silas Malafaia, uno de los l\u00edderes evang\u00e9licos neopentecostales en Brasil, ahora partidario de Jair Bolsonaro, pero que sol\u00eda apoyar a otros gobiernos, me llam\u00f3 \u201cvagabunda\" en una entrevista que concedi\u00f3 a The New York Times. A Malafaia no le gust\u00f3 un art\u00edculo que escrib\u00ed sobre los evang\u00e9licos y reaccion\u00f3 <a href=\"https:\/\/www.nytimes.com\/2011\/11\/26\/world\/americas\/silas-malafaia-tv-evangelist-rises-in-brazils-culture-wars.html\" target=\"_blank\" rel=\"noopener\">llam\u00e1ndome \u201cvagabunda\" en uno de los peri\u00f3dicos m\u00e1s importantes<\/a> del mundo.<\/p>\n<p>Con respecto al trabajo de reporter\u00eda, una vez me pasaron por alto para la cobertura de la guerra con la explicaci\u00f3n de que, profesionalmente, era la mejor opci\u00f3n, pero como mujer, ser\u00eda demasiado peligroso. Entonces decidieron enviar a un hombre. Le respond\u00ed que solo entend\u00eda esa decisi\u00f3n si el periodista elegido necesitaba escribir la historia con su pene. Respond\u00ed a la discriminaci\u00f3n, pero eso no cambi\u00f3 la elecci\u00f3n de mis jefes y, por lo tanto, sufr\u00ed discriminaci\u00f3n, lo que me quit\u00f3 una oportunidad importante.<\/p>\n<p>Otro problema es la falta de apoyo a las mujeres trabajadoras. Tuve una hija a los 15 a\u00f1os y me convert\u00ed en jefa de familia, como sucede con tantas en Brasil y en toda Am\u00e9rica Latina. Mis padres me apoyaron mucho, pero viv\u00edan a seis horas de Porto Alegre, donde trabaj\u00e9 como periodista durante 11 a\u00f1os, antes de mudarme a S\u00e3o Paulo. Tuve que hacer malabares con el trabajo y el cuidado de mi hija despu\u00e9s de que dej\u00f3 la escuela, porque no hab\u00eda apoyo ni ayuda. A las 8 a.m. cuando comenzaba en el peri\u00f3dico, ya hab\u00eda tomado cuatro buses y hab\u00eda caminado mucho, habiendo empezado el d\u00eda a las 5 a.m. para dejar a mi hija afuera de la escuela, donde ella esperaba a que apareciera el portero, sola, y contra la pared, porque el horario del peri\u00f3dico no permit\u00eda cambios.<\/p>\n<p>En otras ocasiones, me he quedado desesperada porque hab\u00eda ido a cubrir una inundaci\u00f3n en un \u00e1rea a tres horas de la ciudad o estaba cubriendo un mot\u00edn en la prisi\u00f3n y no pod\u00eda regresar a tiempo para recoger a mi hija de la escuela. Recuerdo una escena, con el agua hasta la cintura, pegada a un tel\u00e9fono p\u00fablico, porque a\u00fan no exist\u00edan los tel\u00e9fonos celulares, tratando de encontrar un amigo comprensivo que recogiera a mi hija de la escuela, porque solo pod\u00eda regresar a la ciudad por la noche y todav\u00eda ten\u00eda que escribir la historia. Sab\u00edamos, sin necesidad de que nos dijeran, que si necesit\u00e1bamos ausentarnos porque un ni\u00f1o estaba enfermo o si rechaz\u00e1bamos una historia porque no regresar\u00edamos a tiempo para recoger al ni\u00f1o de la escuela o si necesit\u00e1bamos un horario diferente, nos negar\u00edan las historias m\u00e1s interesantes o incluso nos despedir\u00edan. Al mismo tiempo, no hab\u00eda guarder\u00edas ni ning\u00fan tipo de apoyo. Incluso hoy, aunque no se diga, algunos jefes buscan averiguar si existe la posibilidad de un embarazo antes de contratar a una mujer. La discriminaci\u00f3n encuentra muchos caminos, algunos expl\u00edcitos, otros m\u00e1s sutiles, pero permanece muy presente.<\/p>\n<p>Tambi\u00e9n es fundamental darse cuenta de que, si las mujeres est\u00e1n ganando m\u00e1s espacio en las redacciones y el periodismo, como ocurre en diferentes \u00e1mbitos de la sociedad, esto no est\u00e1 sucediendo porque haya una percepci\u00f3n de adentro hacia afuera. Pero lo contrario es cierto. La prensa cambia muy lentamente debido a la presi\u00f3n que viene del exterior. Y, salvo excepciones, en general la prensa sol\u00eda ser, y sigue siendo, bastante conservadora. Y a menudo sexista, mis\u00f3gina, transf\u00f3bica y racista tambi\u00e9n. Si hay muchas mujeres blancas en las salas de redacci\u00f3n de la prensa brasile\u00f1a, rara vez en un puesto de mando, es imperativo darse cuenta de que las mujeres negras y las mujeres trans siguen siendo raras.<\/p>\n<p>Las mujeres no son gen\u00e9ricas. Las mujeres negras sufren mucha m\u00e1s discriminaci\u00f3n que las mujeres blancas, por ejemplo. En un pa\u00eds como Brasil, donde el racismo es estructural, las mujeres negras tienen muchas dificultades para acceder a la educaci\u00f3n y son discriminadas en el mundo laboral no solo por ser mujeres, sino tambi\u00e9n por ser negras. Tambi\u00e9n son las que m\u00e1s mueren en el parto, las que m\u00e1s entierran a los ni\u00f1os por la violencia, las que viven en las casas y regiones m\u00e1s insalubres y sin saneamiento b\u00e1sico. Y tambi\u00e9n las que menos llegan a las oficinas de prensa. Hay un largo camino por recorrer hacia la equidad de g\u00e9nero y raza en nuestro mundo.<\/p>\n<p><strong>LJR: En los \u00faltimos a\u00f1os, la situaci\u00f3n de los periodistas y la prensa en Brasil se ha vuelto m\u00e1s dif\u00edcil. \u00bfCu\u00e1l es su visi\u00f3n del periodismo en el pa\u00eds para los pr\u00f3ximos a\u00f1os?<\/strong><\/p>\n<p><strong>EB:<\/strong> Creo que es importante tener en cuenta que la prensa, en general, tambi\u00e9n es responsable de la crisis de las democracias y de la elecci\u00f3n de neofascistas como Jair Bolsonaro y Donald Trump, entre otros. S\u00ed, existe el fen\u00f3meno de la posverdad, la autoverdad, las noticias falsas, etc. Pero la prensa tambi\u00e9n ha perdido credibilidad ante la poblaci\u00f3n, debido a sus opciones editoriales, comerciales y pol\u00edticas muy poco transparentes. Y porque, en varios pa\u00edses y tambi\u00e9n en Brasil, gran parte de la poblaci\u00f3n no se sinti\u00f3 representada por la cobertura de la prensa ni se reconoci\u00f3 en ella. Sin afrontar estas contradicciones y responsabilidades, ser\u00e1 dif\u00edcil avanzar en un momento tan complejo y dif\u00edcil como el actual.<\/p>\n<p>Las fuerzas neofascistas se dieron cuenta de esta crisis de credibilidad y la utilizaron para debilitar a la prensa y, con la prensa, a la democracia. Pero solo pudieron crear esta industria de hechos alternativos porque la crisis de credibilidad y representaci\u00f3n ya estaba all\u00ed. En la lucha contra d\u00e9spotas electos como Bolsonaro, parte de la prensa est\u00e1 recuperando credibilidad. Pero, como las responsabilidades no fueron reconocidas ni enfrentadas adecuadamente, hay reca\u00eddas monumentales que solo apuntan a que el problema es m\u00e1s antiguo y m\u00e1s complejo. El 29 de mayo, por ejemplo, cientos de miles de brasile\u00f1os ocuparon las calles del pa\u00eds para exigir el juicio pol\u00edtico de Bolsonaro, gritando \u201cFora Bolsonaro\u201d (Fuera Bolsonaro) y \u201cBolsonaro Genocida\u201d. Al d\u00eda siguiente, los titulares de dos de los peri\u00f3dicos m\u00e1s importantes de Brasil ignoraron el evento. En otras palabras: ignor\u00f3 a cientos de miles de brasile\u00f1os que ped\u00edan el juicio pol\u00edtico al presidente. En cambio, el titular principal de uno de ellos fue \u201crecuperaci\u00f3n del PIB\" y del otro ... \u201cturismo\". Entonces, \u00bfc\u00f3mo se recupera la credibilidad con el lector?<\/p>\n<p>Tambi\u00e9n en este a\u00f1o, con una crisis tan profunda, Ag\u00eancia P\u00fablica, una agencia independiente de periodismo de investigaci\u00f3n, realiz\u00f3 un <a href=\"https:\/\/apublica.org\/especial\/caso-k-as-acusacoes-nao-reveladas-de-crimes-sexuais-de-samuel-klein-fundador-da-casas-bahia\/\" target=\"_blank\" rel=\"noopener\">brillante reportaje<\/a>, con un alto nivel de investigaci\u00f3n, sobre el fundador de uno de los principales grupos minoristas del pa\u00eds. Demostr\u00f3 que Samuel Klein, de Casas Bah\u00eda, un \u00edcono del mercado en Brasil, presuntamente viol\u00f3 y abus\u00f3 de ni\u00f1as menores de edad pobres. El informe fue ignorado por la mayor parte de lo que se llama la \u201cgran prensa\u201d o la \u201cprensa tradicional\u201d. Entonces, \u00bfc\u00f3mo se recupera la credibilidad con el lector?<\/p>\n<p>Hago esta larga advertencia porque creo profundamente en el papel fundamental de la prensa para una democracia que merezca ese nombre y me apasiona informar como un documento sobre la historia en movimiento. La prensa deber\u00eda ser mejor, m\u00e1s honesta e inclusiva para recuperar su credibilidad y encarar los inmensos desaf\u00edos de nuestro tiempo. Y cada uno de nosotros tiene un papel en ese trayecto.<\/p>\n<p>Hoy en d\u00eda, hay una parte de la poblaci\u00f3n que no lee, oye ni ve nada producido por la prensa. Ni siquiera hay conflicto, porque esta parte de la poblaci\u00f3n simplemente ignora a la prensa, optando por elegir sus propios hechos, como si eso fuera posible. Sabemos que la negaci\u00f3n de la realidad se enfrenta a los l\u00edmites de la realidad misma. As\u00ed, la \u00fanica forma de afrontar la crisis de la prensa es hacer el mejor periodismo posible, con profundo respeto por los hechos y las personas, afrontando las contradicciones y siendo transparentes sobre los l\u00edmites del periodismo.<\/p>\n<p><strong>LJR: En 2017, se mud\u00f3 de S\u00e3o Paulo, la mayor metr\u00f3polis brasile\u00f1a, a una ciudad del interior del Amazonas, Altamira, en Par\u00e1. Ahora, unos cuatro a\u00f1os despu\u00e9s, \u00bfc\u00f3mo ha afectado este cambio su forma de hacer periodismo? \u00bfC\u00f3mo eval\u00faa hoy su decisi\u00f3n?<\/strong><\/p>\n<p><strong>EB:<\/strong> Me mud\u00e9 de S\u00e3o Paulo a Altamira en agosto de 2017 para ser congruente con lo que creo como periodista y como persona que vive en este momento extremo, expuesto por la emergencia clim\u00e1tica y la sexta extinci\u00f3n masiva de especies, ambas causadas por la acci\u00f3n de una porci\u00f3n de humanos. Por todo lo que estudi\u00e9 e investigu\u00e9 como periodista y por mi experiencia de aprendizaje de m\u00e1s de 20 a\u00f1os cubriendo las diversas Amazon\u00edas (porque son muchas), me parece necesario tener una comprensi\u00f3n diferente de qu\u00e9 es el centro y qu\u00e9 es el periferia. Me parece que los soportes naturales de la vida, como los oc\u00e9anos y las selvas tropicales, deber\u00edan tratarse como centros del mundo porque realmente lo son. Las prioridades de hoy est\u00e1n fuera de lugar, pero debemos restaurarlas y reasignarlas para poder enfrentar los desaf\u00edos sin precedentes de esta era.<\/p>\n<p>Como periodista brasile\u00f1a, nada me parece m\u00e1s esencial que cubrir lo que sucede en la selva tropical m\u00e1s grande del mundo, que est\u00e1 llegando r\u00e1pidamente al punto de no retorno. Investigaciones recientes incluso han demostrado que partes del bosque ya est\u00e1n emitiendo m\u00e1s carbono del que absorbe, lo cual es una noticia terrible para cualquiera que est\u00e9 preocupado por detener nuestra propia extinci\u00f3n. Entonces, si defiendo que el Amazonas est\u00e1 en el centro -y no porque me lo saque de la cabeza, sino porque eso es lo que me dice mi investigaci\u00f3n period\u00edstica-, entonces \u00bfc\u00f3mo voy a seguir cubriendo el Amazonas desde S\u00e3o Paulo?<\/p>\n<p>Me mud\u00e9 a Altamira, una de las ciudades m\u00e1s violentas de la Amazon\u00eda y uno de los epicentros de la destrucci\u00f3n, para ver el planeta desde la Amazon\u00eda. Este cambio que defiendo como concepto y que hice con mi propio cuerpo ha transformado profundamente mi forma de entender el bosque, el planeta y a m\u00ed misma. Esto ha mejorado y ampliado la profundidad de mi periodismo, porque ya no soy una \u201cenviada especial\u201d a la Amazon\u00eda. Eventualmente puedo ser una enviada especial a S\u00e3o Paulo, Brasilia o Washington. Pero investigo la Amazon\u00eda desde adentro y miro el mundo desde esta. Esta elecci\u00f3n incluso cambi\u00f3 mi propio idioma y mi forma de habitar el planeta. Por supuesto, hubo un gran costo personal, pero tambi\u00e9n hubo una gran ganancia personal. Este viaje period\u00edstico est\u00e1 narrado en un libro que ser\u00e1 lanzado a finales de este mes, en Brasil, por la editorial Companhia das Letras, y ser\u00e1 lanzado en Estados Unidos en 2023, por Graywolf.<\/p>\n<p>&nbsp;<\/p>\n<p><em>* Nota editorial: Rosental Alves, presidente del Consejo de los Premios Cabot, es fundador y director del Centro Knight para el Periodismo en las Am\u00e9ricas que publica LatAm Journalism Review.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la entrevista, Brum habla sobre las veces que sufri\u00f3 acoso sexual y discriminaci\u00f3n en las redacciones brasile\u00f1as, sobre la experiencia de ser madre a los 15 a\u00f1os y la falta de apoyo en el trabajo, adem\u00e1s de la decisi\u00f3n de mudarse a Altamira, al interior del Amazonas.<\/p>\n","protected":false},"author":6,"featured_media":35237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1354],"tags":[1428],"coauthors":[],"class_list":["post-35811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-oportunidades-es","tag-premios-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot - LatAm Journalism Review<\/title>\n<meta name=\"description\" content=\"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot\" \/>\n<meta property=\"og:description\" content=\"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Journalism Review\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-05T19:30:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-17T17:13:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Featured-Adriana-Zehbrauskas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"507\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marina Estarque\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MarinaEstarque\" \/>\n<meta name=\"twitter:site\" content=\"@LatAmJournalism\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina Estarque\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/\"},\"author\":{\"name\":\"Marina Estarque\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/person\\\/041964d0921c867b6226b459cd5bf28b\"},\"headline\":\"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot\",\"datePublished\":\"2021-10-05T19:30:52+00:00\",\"dateModified\":\"2021-12-17T17:13:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/\"},\"wordCount\":2644,\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Featured-Adriana-Zehbrauskas.png\",\"keywords\":[\"Premios\"],\"articleSection\":[\"Premios y oportunidades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/\",\"name\":\"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot - LatAm Journalism Review\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Featured-Adriana-Zehbrauskas.png\",\"datePublished\":\"2021-10-05T19:30:52+00:00\",\"dateModified\":\"2021-12-17T17:13:43+00:00\",\"description\":\"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Featured-Adriana-Zehbrauskas.png\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Featured-Adriana-Zehbrauskas.png\",\"width\":507,\"height\":340,\"caption\":\"A jornalista, escritora e documentarista brasileira Eliane Brum, uma das ganhadoras dos Pr\u00eamios Maria Moors Cabot de 2021. Foto: Azul Serra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/\",\"name\":\"LatAm Journalism Review\",\"description\":\"Knight Center at The University of Texas\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#organization\",\"name\":\"LatAm Journalism Review\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"LatAm Journalism Review\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/LatAmJournalism\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/person\\\/041964d0921c867b6226b459cd5bf28b\",\"name\":\"Marina Estarque\",\"description\":\"Marina Estarque is a Brazilian journalist living in S\u00e3o Paulo. She has worked for Brazilian news organizations such as Folha de S.Paulo, O Estado de S. Paulo, O Dia and the fact-checking agency Lupa. Marina was a correspondent in Brazil for the German international broadcaster Deutsche Welle and a radio reporter for DW Africa in Germany. She also worked as a reporter for United Nations Radio, in New York, and for Spanish newspaper La Voz de Galicia. Marina graduated in Journalism from the Federal University of Rio de Janeiro and has a Master\u2019s degree in Editorial Journalism from the University of A Coru\u00f1a (Spain). Marina Estarque es una periodista brasile\u00f1a que vive en S\u00e3o Paulo. Ella ha trabajado para diversas organizaciones period\u00edsticas como Folha de S.Paulo, O Estado de S. Paulo, O Dia y en la agencia de fact-checking Lupa. Marina ha sido corresponsal en Brasil del canal internacional alem\u00e1n Deutsche Welle y reportera de radio de DW \u00c1frica en Alemania. Tambi\u00e9n trabaj\u00f3 como reportera de Radio de las Naciones Unidas en Nueva York y en el diario espa\u00f1ol La Voz de Galicia. Marina tiene una maestr\u00eda en edici\u00f3n period\u00edstica de la Universidad de Coru\u00f1a (Espa\u00f1a) y se gradu\u00f3 en periodismo en la Universidad Federal de R\u00edo de Janeiro. Marina Estarque \u00e9 uma jornalista brasileira que vive em S\u00e3o Paulo. Ela trabalhou para ve\u00edculos como Folha de S.Paulo, O Estado de S. Paulo, O Dia e a ag\u00eancia de fact-checking Lupa. Marina foi correspondente no Brasil para a emissora internacional da Alemanha, a Deutsche Welle, e rep\u00f3rter de r\u00e1dio para a DW \u00c1frica na Alemanha. Ela tamb\u00e9m foi rep\u00f3rter da R\u00e1dio das Na\u00e7\u00f5es Unidas em Nova York e do jornal espanhol La Voz de Galicia. Marina \u00e9 mestre em edi\u00e7\u00e3o jornal\u00edstica pela Universidade da Coru\u00f1a (Espanha) e graduada em jornalismo pela Universidade Federal do Rio de Janeiro.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/MarinaEstarque\"],\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/author\\\/marina-estarque\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot - LatAm Journalism Review","description":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/","og_locale":"es_ES","og_type":"article","og_title":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot","og_description":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","og_url":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/","og_site_name":"LatAm Journalism Review","article_published_time":"2021-10-05T19:30:52+00:00","article_modified_time":"2021-12-17T17:13:43+00:00","og_image":[{"width":507,"height":340,"url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Featured-Adriana-Zehbrauskas.png","type":"image\/png"}],"author":"Marina Estarque","twitter_card":"summary_large_image","twitter_creator":"@MarinaEstarque","twitter_site":"@LatAmJournalism","twitter_misc":{"Written by":"Marina Estarque","Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/#article","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/"},"author":{"name":"Marina Estarque","@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/person\/041964d0921c867b6226b459cd5bf28b"},"headline":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot","datePublished":"2021-10-05T19:30:52+00:00","dateModified":"2021-12-17T17:13:43+00:00","mainEntityOfPage":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/"},"wordCount":2644,"publisher":{"@id":"https:\/\/latamjournalismreview.org\/es\/#organization"},"image":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/#primaryimage"},"thumbnailUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Featured-Adriana-Zehbrauskas.png","keywords":["Premios"],"articleSection":["Premios y oportunidades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/","url":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/","name":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot - LatAm Journalism Review","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/#primaryimage"},"image":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/#primaryimage"},"thumbnailUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Featured-Adriana-Zehbrauskas.png","datePublished":"2021-10-05T19:30:52+00:00","dateModified":"2021-12-17T17:13:43+00:00","description":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","breadcrumb":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/#primaryimage","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Featured-Adriana-Zehbrauskas.png","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2021\/10\/Featured-Adriana-Zehbrauskas.png","width":507,"height":340,"caption":"A jornalista, escritora e documentarista brasileira Eliane Brum, uma das ganhadoras dos Pr\u00eamios Maria Moors Cabot de 2021. Foto: Azul Serra"},{"@type":"BreadcrumbList","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/prensa-es-responsable-de-crisis-de-la-democracia-y-de-eleccion-de-bolsonaro-y-trump-dice-eliane-brum-ganadora-del-premio-cabot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamjournalismreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"Prensa tambi\u00e9n es responsable por la crisis de la democracia y por elecci\u00f3n de Bolsonaro y Trump, dice Eliane Brum, ganadora del Premio Cabot"}]},{"@type":"WebSite","@id":"https:\/\/latamjournalismreview.org\/es\/#website","url":"https:\/\/latamjournalismreview.org\/es\/","name":"LatAm Journalism Review","description":"Knight Center at The University of Texas","publisher":{"@id":"https:\/\/latamjournalismreview.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamjournalismreview.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/latamjournalismreview.org\/es\/#organization","name":"LatAm Journalism Review","url":"https:\/\/latamjournalismreview.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","width":"1024","height":"1024","caption":"LatAm Journalism Review"},"image":{"@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/LatAmJournalism"]},{"@type":"Person","@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/person\/041964d0921c867b6226b459cd5bf28b","name":"Marina Estarque","description":"Marina Estarque is a Brazilian journalist living in S\u00e3o Paulo. She has worked for Brazilian news organizations such as Folha de S.Paulo, O Estado de S. Paulo, O Dia and the fact-checking agency Lupa. Marina was a correspondent in Brazil for the German international broadcaster Deutsche Welle and a radio reporter for DW Africa in Germany. She also worked as a reporter for United Nations Radio, in New York, and for Spanish newspaper La Voz de Galicia. Marina graduated in Journalism from the Federal University of Rio de Janeiro and has a Master\u2019s degree in Editorial Journalism from the University of A Coru\u00f1a (Spain). Marina Estarque es una periodista brasile\u00f1a que vive en S\u00e3o Paulo. Ella ha trabajado para diversas organizaciones period\u00edsticas como Folha de S.Paulo, O Estado de S. Paulo, O Dia y en la agencia de fact-checking Lupa. Marina ha sido corresponsal en Brasil del canal internacional alem\u00e1n Deutsche Welle y reportera de radio de DW \u00c1frica en Alemania. Tambi\u00e9n trabaj\u00f3 como reportera de Radio de las Naciones Unidas en Nueva York y en el diario espa\u00f1ol La Voz de Galicia. Marina tiene una maestr\u00eda en edici\u00f3n period\u00edstica de la Universidad de Coru\u00f1a (Espa\u00f1a) y se gradu\u00f3 en periodismo en la Universidad Federal de R\u00edo de Janeiro. Marina Estarque \u00e9 uma jornalista brasileira que vive em S\u00e3o Paulo. Ela trabalhou para ve\u00edculos como Folha de S.Paulo, O Estado de S. Paulo, O Dia e a ag\u00eancia de fact-checking Lupa. Marina foi correspondente no Brasil para a emissora internacional da Alemanha, a Deutsche Welle, e rep\u00f3rter de r\u00e1dio para a DW \u00c1frica na Alemanha. Ela tamb\u00e9m foi rep\u00f3rter da R\u00e1dio das Na\u00e7\u00f5es Unidas em Nova York e do jornal espanhol La Voz de Galicia. Marina \u00e9 mestre em edi\u00e7\u00e3o jornal\u00edstica pela Universidade da Coru\u00f1a (Espanha) e graduada em jornalismo pela Universidade Federal do Rio de Janeiro.","sameAs":["https:\/\/x.com\/MarinaEstarque"],"url":"https:\/\/latamjournalismreview.org\/es\/articles\/author\/marina-estarque\/"}]}},"_links":{"self":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts\/35811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/comments?post=35811"}],"version-history":[{"count":13,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts\/35811\/revisions"}],"predecessor-version":[{"id":45769,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts\/35811\/revisions\/45769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/media\/35237"}],"wp:attachment":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/media?parent=35811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/categories?post=35811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/tags?post=35811"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/coauthors?post=35811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}