{"id":8857,"date":"2020-07-16T19:01:53","date_gmt":"2020-07-17T00:01:53","guid":{"rendered":"https:\/\/latamjournalismreview.org\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/"},"modified":"2020-10-07T22:48:45","modified_gmt":"2020-10-08T03:48:45","slug":"veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020","status":"publish","type":"post","link":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/","title":{"rendered":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El <a href=\"http:\/\/stephenferry.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">fotoperiodista estadounidense Stephen Ferry<\/a>, que vive y trabaja en Colombia, fue uno de los ganadores del <a href=\"https:\/\/latamjournalismreview.org\/es\/articles\/premios-maria-moors-cabot-2020-reconocen-a-reporteros-de-brasil-colombia-y-estados-unidos\/\" target=\"_blank\" rel=\"noopener noreferrer\">premio Maria Moors Cabot 2020, anunciado este 15 de juli<\/a>o. En el anuncio de los ganadores, Ferry es descrito como un reportero gr\u00e1fico \u201ccon la paciencia de un antrop\u00f3logo y una gran humanidad\u201d, que se ha dedicado durante m\u00e1s de tres d\u00e9cadas a proyectos que se han convertido en \u201cmodelos de fotoperiodismo inmersivo\u201d.<\/span><\/p>\n<div id=\"attachment_8755\" style=\"width: 410px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8755\" class=\"wp-image-8756\" src=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Photo-by-Romana-Vysatova-300x200.jpg\" alt=\"Stephen Ferry\" width=\"400\" height=\"266\" srcset=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Photo-by-Romana-Vysatova-300x200.jpg 300w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Photo-by-Romana-Vysatova-1024x683.jpg 1024w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Photo-by-Romana-Vysatova-768x512.jpg 768w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><p id=\"caption-attachment-8755\" class=\"wp-caption-text\">Stephen Ferry (Photo: Romana Vysatova)<\/p><\/div>\n<p><span style=\"font-weight: 400;\">En una entrevista con <\/span><strong>LatAm Journalism Review<\/strong><span style=\"font-weight: 400;\">, Ferry dijo que considera su trabajo \u201can\u00e1logo a la antropolog\u00eda forense\u201d, en el sentido de revelar violaciones de derechos humanos que los criminales buscan ocultar. Tambi\u00e9n habla sobre el ritmo de su trabajo, la inmersi\u00f3n y las formas de encontrar fondos para este tipo de proyectos. Ferry tambi\u00e9n dijo que ve un \u201cboom creativo\u201d en el medio fotogr\u00e1fico y documental en Am\u00e9rica Latina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El reportero gr\u00e1fico es profesor de la Fundaci\u00f3n Gabo \u2013 antes Fundaci\u00f3n Gabriel Garc\u00eda M\u00e1rquez para el Nuevo Periodismo Iberoamericano \u2013\u00a0 y su trabajo ha aparecido en varias publicaciones como The New Yorker, The New York Times, GEO, TIME, National Geographic, entre otras.<\/span><\/p>\n<p><strong>LJR: \u00bfQu\u00e9 significa para usted el premio Maria Moors Cabot? \u00bfC\u00f3mo se siente tras recibirlo?<\/strong><\/p>\n<p><strong>SF:<\/strong><span style=\"font-weight: 400;\"> Aunque no pienso mucho en los premios de periodismo, siempre consider\u00e9 importante el premio Cabot porque ve\u00eda la calidad de los colegas que lo hab\u00edan ganado. Recuerdo hace d\u00e9cadas, cuando Alma Guillermoprieto y Susan Meiselas ganaron este premio, quienes tuvieron una gran influencia en mi propio camino, pensaba en el honor que ser\u00eda compartir esa distinci\u00f3n. Tambi\u00e9n estoy feliz de ser reconocido como reportero gr\u00e1fico. Es genial que la profesi\u00f3n entienda el valor de nuestro trabajo y vea el fotoperiodismo como algo tan importante como otras formas de periodismo.<\/span><\/p>\n<p><strong>LJR: \u00bfQu\u00e9 significa para Ud. ser fotoperiodista en Colombia (y en otros pa\u00edses donde trabaja) y el tipo de periodismo que hace?<\/strong><\/p>\n<p><strong>SF:<\/strong><span style=\"font-weight: 400;\"> Colombia es un lugar particularmente desafiante para trabajar como fotoperiodista porque hay muchas suposiciones por ah\u00ed. Para hacer justicia a las complejidades del pa\u00eds y, en particular, para informar sobre el conflicto armado interno de Colombia, terminas nadando contra la corriente. La suposici\u00f3n generalizada es que la ra\u00edz de la violencia social y pol\u00edtica de Colombia es el narcotr\u00e1fico. Esta idea simplista probablemente dice m\u00e1s sobre las prioridades de la pol\u00edtica exterior de Estados Unidos que sobre la realidad. Las ra\u00edces del conflicto son m\u00e1s antiguas que el narcotr\u00e1fico y son extremadamente complejas. Para lidiar con esto, trabaj\u00e9 para encontrar un vocabulario visual que reflejara esta complejidad y ambig\u00fcedad y no dependiera de las ideas recibidas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo mismo podr\u00eda decirse de mi trabajo sobre la miner\u00eda de oro. Los observadores y las partes interesadas a menudo usan lenguaje escrito y visual para retratar a los peque\u00f1os mineros de una manera estigmatizante. La miner\u00eda de oro es un tema muy controvertido, y lleva tiempo ir m\u00e1s all\u00e1 de ciertas categor\u00edas, como \u201cminer\u00eda ilegal\u201d, que pueden oscurecer m\u00e1s de lo que revelan. Una buena fotograf\u00eda consiste en prestar atenci\u00f3n a los detalles en lugar de ilustrar ideas preconcebidas. Quiz\u00e1s una de las razones por las que me gusta trabajar en Colombia es que me reta a trabajar contra la corriente.<\/span><\/p>\n<p><strong>LJR: Cuando piensa en todas las personas que ha fotografiado y en todas las historias que ha cubierto, \u00bfcu\u00e1les dir\u00eda que fueron las m\u00e1s interesantes o de las que aprendi\u00f3 m\u00e1s?<\/strong><\/p>\n<p><strong>SF:<\/strong> <span style=\"font-weight: 400;\">Veo el trabajo como un proceso colaborativo. Por ejemplo, cuando cubr\u00ed la exhumaci\u00f3n de la masacre de El Mozote en El Salvador en 1993, aprend\u00ed mucho de la ONG Equipo Argentino de Antropolog\u00eda Forense (EAAF) que realiz\u00f3 las investigaciones. Los antrop\u00f3logos hacen visible la evidencia que los asesinos han escondido para evitar el conocimiento p\u00fablico de sus cr\u00edmenes. Cuando se revelan los huesos, es posible que la sociedad busque justicia, que los miembros de la familia descubran lo que sucedi\u00f3 y lloren por sus muertos, y que el p\u00fablico descubra la verdad de lo que sucedi\u00f3. Desde entonces, veo mi trabajo como fot\u00f3grafo como an\u00e1logo a la antropolog\u00eda forense, al menos en lo que respecta a cuestiones de derechos humanos. Lo que aprend\u00ed trabajando junto al EAAF en El Salvador ha influido en mi trabajo hasta el d\u00eda de hoy, especialmente porque la antropolog\u00eda forense juega un papel clave en el proceso de paz en Colombia, como lo hizo en El Salvador.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En 2002, comenc\u00e9 a trabajar en un art\u00edculo sobre las culturas ancestrales de la Sierra Nevada de Santa Marta, en el norte de Colombia, en una misi\u00f3n para National Geographic. Este trabajo s\u00f3lo fue posible gracias a la colaboraci\u00f3n con organizaciones ind\u00edgenas de monta\u00f1a cuando acordamos que compartir\u00eda los resultados de mi trabajo como propiedad colectiva de los pueblos ind\u00edgenas. Afortunadamente, m\u00e1s tarde pude ayudar a las organizaciones ind\u00edgenas a formar un equipo de documentalistas ind\u00edgenas, bajo el liderazgo del director y fot\u00f3grafo Arhuaco Amado Villafa\u00f1a, y desde entonces hemos trabajado juntos en proyectos. Esa fue una gran lecci\u00f3n para m\u00ed sobre la importancia de reconocer mi propia ignorancia y trabajar en colaboraci\u00f3n, en lugar de s\u00f3lo intentar entrar, tomar algunas fotos ex\u00f3ticas y salir.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante m\u00e1s de diez a\u00f1os cubriendo el conflicto armado interno de Colombia aprend\u00ed una y otra vez la importancia de colaborar. Quiz\u00e1s debido a que los periodistas colombianos trabajan en circunstancias tan dif\u00edciles, existe una gran solidaridad entre los colegas, lo que hace que el trabajo sea infinitamente m\u00e1s rico y, por supuesto, ofrece una medida de protecci\u00f3n. Desde mis primeras visitas a Colombia, cuando me invitaron a impartir talleres en la Fundaci\u00f3n para el Nuevo Periodismo Iberoamericano [ahora Fundaci\u00f3n Gabo], fundada por Gabriel Garc\u00eda M\u00e1rquez, sent\u00ed este esp\u00edritu de cooperaci\u00f3n y apoyo mutuo caracter\u00edstico del periodismo en Colombia.<\/span><\/p>\n<p><strong>LJR: Como profesor, \u00bfc\u00f3mo ve a la pr\u00f3xima generaci\u00f3n de reporteros gr\u00e1ficos? \u00bfY qu\u00e9 consejo le da a sus alumnos?<\/strong><\/p>\n<p><strong>SF:<\/strong> <span style=\"font-weight: 400;\">Soy cautelosamente optimista sobre el futuro del fotoperiodismo en Am\u00e9rica Latina. Por un lado, la profesi\u00f3n sigue siendo gran parte machista, que tiene muchas barreras de entrada para las mujeres. El sexismo sigue rampante en muchos departamentos de fotograf\u00eda. Por otro lado, muchas mujeres est\u00e1n desafiando esta situaci\u00f3n y cada vez m\u00e1s se ve a las mujeres fot\u00f3grafas ganando reconocimiento por su valor. Tambi\u00e9n hay organizaciones importantes que est\u00e1n trabajando para aumentar la diversidad de g\u00e9nero y racial en el campo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La ecuaci\u00f3n econ\u00f3mica es dif\u00edcil. Al igual que en Estados Unidos, el capital est\u00e1 altamente concentrado en el negocio de las noticias y el pago para los fot\u00f3grafos, como para los periodistas, es absurdamente bajo. Hay menos publicaciones que en el pasado y las prioridades de los editores siguen cambiando hacia contenido que les cuesta poco o nada adquirir. Lo que ha cambiado para mejor es que los medios internacionales ahora contratan y pagan a los fot\u00f3grafos locales al mismo ritmo que a los extranjeros, y hay muchos m\u00e1s latinoamericanos que trabajan con publicaciones estadounidenses y europeas que antes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Actualmente, se est\u00e1 realizando un incre\u00edble trabajo fotogr\u00e1fico en toda Am\u00e9rica Latina, quiz\u00e1s m\u00e1s en una vena documental en profundidad que en el fotoperiodismo <\/span><i><span style=\"font-weight: 400;\">per se<\/span><\/i><span style=\"font-weight: 400;\">. En este sentido, Am\u00e9rica Latina est\u00e1 experimentando una especie de auge creativo y existe un di\u00e1logo entre fot\u00f3grafos documentales, escritores y editores de libros que es muy emocionante. Con un grupo de fot\u00f3grafos, ayud\u00e9 a fundar <a href=\"https:\/\/www.facebook.com\/ojorojofabricavisual\/\" target=\"_blank\" rel=\"noopener noreferrer\">OjoRojo, un espacio comunitario en Bogot\u00e1<\/a>, que se dedica a promover una conversaci\u00f3n creativa entre reporteros gr\u00e1ficos, fot\u00f3grafos documentales y el p\u00fablico. Hay una serie de iniciativas como OjoRojo en toda Am\u00e9rica Latina que hablan de este momento creativo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mi consejo en general para los estudiantes de fotoperiodismo es buscar colaboraciones con organizaciones sociales, grupos de la sociedad civil, escritores, cient\u00edficos, artistas, dise\u00f1adores gr\u00e1ficos, etc. Cada vez m\u00e1s, los periodistas independientes realizan el fotoperiodismo a medida que se recortan los presupuestos, el personal disminuye y cierran publicaciones. En estas condiciones, a menudo es demasiado dif\u00edcil y demasiado solitario trabajar completamente por su cuenta. Aunque ciertamente hay un papel para proyectos altamente individuales, en general, creo que hoy en d\u00eda uno funciona mejor trabajando en proyectos con otras personas. Un gran ejemplo de ese tipo de colaboraci\u00f3n ser\u00eda El Faro en El Salvador.<\/span><\/p>\n<p><strong>LJR: En un momento en que todo parece hecho para el consumo inmediato, incluidas las noticias, Ud. se dedica al fotoperiodismo inmersivo. \u00bfPor qu\u00e9 le gusta este tipo de trabajo y cu\u00e1l es la importancia?\u00a0<\/strong><\/p>\n<p><strong>SF:<\/strong><span style=\"font-weight: 400;\"> Quiz\u00e1s s\u00f3lo soy lento por naturaleza. Ciertamente respeto a los colegas que hacen un excelente trabajo de noticias puntuales y pueden archivar desde el campo usando su tel\u00e9fono celular para editar y escribir subt\u00edtulos y listo. Hay muchos enfoques v\u00e1lidos para el trabajo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En general, mi proceso es comenzar a trabajar en una historia, y luego se me mete en la piel y empiezo a buscar nuevas asignaciones o subvenciones para financiar el regreso y obsesionarme con eso. Debido a que lleva tiempo encontrar los recursos, el ritmo puede ser frustrante, pero termina teniendo una visi\u00f3n m\u00e1s longitudinal de lo que hubiera tenido de otra manera. Por ejemplo, <\/span><i><span style=\"font-weight: 400;\">Violentology: A Manual of the Colombian Conflict<\/span><\/i><span style=\"font-weight: 400;\"> (Violentolog\u00eda: un manual del conflicto colombiano) tard\u00f3 m\u00e1s de doce a\u00f1os en completarse, pero al final el libro cubre el periodo desde el v\u00e9rtice de las Farc hasta la ofensiva paramilitar que casi se apoder\u00f3 de Colombia hasta el comienzo del proceso de paz. Del mismo modo, La Batea analiza la extracci\u00f3n de oro durante un periodo de cinco a\u00f1os, y sucedi\u00f3 mucho durante ese tiempo para lograr una comprensi\u00f3n m\u00e1s matizada de la historia. Mientras estoy construyendo el trabajo m\u00e1s amplio, busco distribuir y publicar partes de \u00e9l en forma de ensayo como una forma de financiar el proyecto y mantenerme actualizado.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><em>Este art\u00edculo fue escrito originalmente en portugu\u00e9s y traducido por Silvia Higuera<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stephen Ferry, cuya carrera abarca m\u00e1s de tres d\u00e9cadas, es descrito como un reportero gr\u00e1fico \u201ccon la paciencia de un antrop\u00f3logo y una gran humanidad\u201d, por la Columbia Journalism School.<\/p>\n","protected":false},"author":6,"featured_media":8768,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1354],"tags":[1395,1506,1428],"coauthors":[],"class_list":["post-8857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-oportunidades-es","tag-colombia-es-2","tag-fotoperiodismo-es","tag-premios-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 - LatAm Journalism Review<\/title>\n<meta name=\"description\" content=\"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020\" \/>\n<meta property=\"og:description\" content=\"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Journalism Review\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-17T00:01:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T03:48:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Stephen-Ferry.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1101\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marina Estarque\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MarinaEstarque\" \/>\n<meta name=\"twitter:site\" content=\"@LatAmJournalism\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina Estarque\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/\"},\"author\":{\"name\":\"Marina Estarque\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/person\\\/041964d0921c867b6226b459cd5bf28b\"},\"headline\":\"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020\",\"datePublished\":\"2020-07-17T00:01:53+00:00\",\"dateModified\":\"2020-10-08T03:48:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/\"},\"wordCount\":1800,\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Stephen-Ferry.jpg\",\"keywords\":[\"Colombia\",\"Fotoperiodismo\",\"Premios\"],\"articleSection\":[\"Premios y oportunidades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/\",\"name\":\"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 - LatAm Journalism Review\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Stephen-Ferry.jpg\",\"datePublished\":\"2020-07-17T00:01:53+00:00\",\"dateModified\":\"2020-10-08T03:48:45+00:00\",\"description\":\"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Stephen-Ferry.jpg\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Stephen-Ferry.jpg\",\"width\":1101,\"height\":731,\"caption\":\"Stephen Ferry (Photo: Romana Vysatova)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/\",\"name\":\"LatAm Journalism Review\",\"description\":\"Knight Center at The University of Texas\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#organization\",\"name\":\"LatAm Journalism Review\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"LatAm Journalism Review\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/LatAmJournalism\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/#\\\/schema\\\/person\\\/041964d0921c867b6226b459cd5bf28b\",\"name\":\"Marina Estarque\",\"description\":\"Marina Estarque is a Brazilian journalist living in S\u00e3o Paulo. She has worked for Brazilian news organizations such as Folha de S.Paulo, O Estado de S. Paulo, O Dia and the fact-checking agency Lupa. Marina was a correspondent in Brazil for the German international broadcaster Deutsche Welle and a radio reporter for DW Africa in Germany. She also worked as a reporter for United Nations Radio, in New York, and for Spanish newspaper La Voz de Galicia. Marina graduated in Journalism from the Federal University of Rio de Janeiro and has a Master\u2019s degree in Editorial Journalism from the University of A Coru\u00f1a (Spain). Marina Estarque es una periodista brasile\u00f1a que vive en S\u00e3o Paulo. Ella ha trabajado para diversas organizaciones period\u00edsticas como Folha de S.Paulo, O Estado de S. Paulo, O Dia y en la agencia de fact-checking Lupa. Marina ha sido corresponsal en Brasil del canal internacional alem\u00e1n Deutsche Welle y reportera de radio de DW \u00c1frica en Alemania. Tambi\u00e9n trabaj\u00f3 como reportera de Radio de las Naciones Unidas en Nueva York y en el diario espa\u00f1ol La Voz de Galicia. Marina tiene una maestr\u00eda en edici\u00f3n period\u00edstica de la Universidad de Coru\u00f1a (Espa\u00f1a) y se gradu\u00f3 en periodismo en la Universidad Federal de R\u00edo de Janeiro. Marina Estarque \u00e9 uma jornalista brasileira que vive em S\u00e3o Paulo. Ela trabalhou para ve\u00edculos como Folha de S.Paulo, O Estado de S. Paulo, O Dia e a ag\u00eancia de fact-checking Lupa. Marina foi correspondente no Brasil para a emissora internacional da Alemanha, a Deutsche Welle, e rep\u00f3rter de r\u00e1dio para a DW \u00c1frica na Alemanha. Ela tamb\u00e9m foi rep\u00f3rter da R\u00e1dio das Na\u00e7\u00f5es Unidas em Nova York e do jornal espanhol La Voz de Galicia. Marina \u00e9 mestre em edi\u00e7\u00e3o jornal\u00edstica pela Universidade da Coru\u00f1a (Espanha) e graduada em jornalismo pela Universidade Federal do Rio de Janeiro.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/MarinaEstarque\"],\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/es\\\/articles\\\/author\\\/marina-estarque\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 - LatAm Journalism Review","description":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020","og_description":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","og_url":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/","og_site_name":"LatAm Journalism Review","article_published_time":"2020-07-17T00:01:53+00:00","article_modified_time":"2020-10-08T03:48:45+00:00","og_image":[{"width":1101,"height":731,"url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Stephen-Ferry.jpg","type":"image\/jpeg"}],"author":"Marina Estarque","twitter_card":"summary_large_image","twitter_creator":"@MarinaEstarque","twitter_site":"@LatAmJournalism","twitter_misc":{"Written by":"Marina Estarque","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/#article","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/"},"author":{"name":"Marina Estarque","@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/person\/041964d0921c867b6226b459cd5bf28b"},"headline":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020","datePublished":"2020-07-17T00:01:53+00:00","dateModified":"2020-10-08T03:48:45+00:00","mainEntityOfPage":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/"},"wordCount":1800,"publisher":{"@id":"https:\/\/latamjournalismreview.org\/es\/#organization"},"image":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Stephen-Ferry.jpg","keywords":["Colombia","Fotoperiodismo","Premios"],"articleSection":["Premios y oportunidades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/","url":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/","name":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 - LatAm Journalism Review","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/#primaryimage"},"image":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Stephen-Ferry.jpg","datePublished":"2020-07-17T00:01:53+00:00","dateModified":"2020-10-08T03:48:45+00:00","description":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020 Premios y oportunidades. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","breadcrumb":{"@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/#primaryimage","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Stephen-Ferry.jpg","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/07\/Stephen-Ferry.jpg","width":1101,"height":731,"caption":"Stephen Ferry (Photo: Romana Vysatova)"},{"@type":"BreadcrumbList","@id":"https:\/\/latamjournalismreview.org\/es\/articles\/veo-mi-trabajo-como-analogo-a-la-antropologia-forense-dice-el-fotoperiodista-stephen-ferry-ganador-del-maria-moors-cabot-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamjournalismreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u201cVeo mi trabajo como an\u00e1logo a la antropolog\u00eda forense\u201d, dice el fotoperiodista Stephen Ferry, ganador del Maria Moors Cabot 2020"}]},{"@type":"WebSite","@id":"https:\/\/latamjournalismreview.org\/es\/#website","url":"https:\/\/latamjournalismreview.org\/es\/","name":"LatAm Journalism Review","description":"Knight Center at The University of Texas","publisher":{"@id":"https:\/\/latamjournalismreview.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamjournalismreview.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/latamjournalismreview.org\/es\/#organization","name":"LatAm Journalism Review","url":"https:\/\/latamjournalismreview.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","width":"1024","height":"1024","caption":"LatAm Journalism Review"},"image":{"@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/LatAmJournalism"]},{"@type":"Person","@id":"https:\/\/latamjournalismreview.org\/es\/#\/schema\/person\/041964d0921c867b6226b459cd5bf28b","name":"Marina Estarque","description":"Marina Estarque is a Brazilian journalist living in S\u00e3o Paulo. She has worked for Brazilian news organizations such as Folha de S.Paulo, O Estado de S. Paulo, O Dia and the fact-checking agency Lupa. Marina was a correspondent in Brazil for the German international broadcaster Deutsche Welle and a radio reporter for DW Africa in Germany. She also worked as a reporter for United Nations Radio, in New York, and for Spanish newspaper La Voz de Galicia. Marina graduated in Journalism from the Federal University of Rio de Janeiro and has a Master\u2019s degree in Editorial Journalism from the University of A Coru\u00f1a (Spain). Marina Estarque es una periodista brasile\u00f1a que vive en S\u00e3o Paulo. Ella ha trabajado para diversas organizaciones period\u00edsticas como Folha de S.Paulo, O Estado de S. Paulo, O Dia y en la agencia de fact-checking Lupa. Marina ha sido corresponsal en Brasil del canal internacional alem\u00e1n Deutsche Welle y reportera de radio de DW \u00c1frica en Alemania. Tambi\u00e9n trabaj\u00f3 como reportera de Radio de las Naciones Unidas en Nueva York y en el diario espa\u00f1ol La Voz de Galicia. Marina tiene una maestr\u00eda en edici\u00f3n period\u00edstica de la Universidad de Coru\u00f1a (Espa\u00f1a) y se gradu\u00f3 en periodismo en la Universidad Federal de R\u00edo de Janeiro. Marina Estarque \u00e9 uma jornalista brasileira que vive em S\u00e3o Paulo. Ela trabalhou para ve\u00edculos como Folha de S.Paulo, O Estado de S. Paulo, O Dia e a ag\u00eancia de fact-checking Lupa. Marina foi correspondente no Brasil para a emissora internacional da Alemanha, a Deutsche Welle, e rep\u00f3rter de r\u00e1dio para a DW \u00c1frica na Alemanha. Ela tamb\u00e9m foi rep\u00f3rter da R\u00e1dio das Na\u00e7\u00f5es Unidas em Nova York e do jornal espanhol La Voz de Galicia. Marina \u00e9 mestre em edi\u00e7\u00e3o jornal\u00edstica pela Universidade da Coru\u00f1a (Espanha) e graduada em jornalismo pela Universidade Federal do Rio de Janeiro.","sameAs":["https:\/\/x.com\/MarinaEstarque"],"url":"https:\/\/latamjournalismreview.org\/es\/articles\/author\/marina-estarque\/"}]}},"_links":{"self":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts\/8857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/comments?post=8857"}],"version-history":[{"count":9,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts\/8857\/revisions"}],"predecessor-version":[{"id":12052,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/posts\/8857\/revisions\/12052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/media\/8768"}],"wp:attachment":[{"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/media?parent=8857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/categories?post=8857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/tags?post=8857"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/es\/wp-json\/wp\/v2\/coauthors?post=8857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}