{"id":31945,"date":"2012-06-27T20:21:56","date_gmt":"2012-06-28T01:21:56","guid":{"rendered":"https:\/\/latamjournalismreview.org\/?p=31945"},"modified":"2021-09-16T20:24:39","modified_gmt":"2021-09-17T01:24:39","slug":"no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados","status":"publish","type":"post","link":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/","title":{"rendered":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados"},"content":{"rendered":"<p>Cerca de 200 pessoas trabalham no\u00a0<a href=\"http:\/\/reporteindigo.com\/reporte\/mexico\/no-se-mata-la-verdad-matando-periodistas\" target=\"_blank\" rel=\"noopener\">livro \u201cN\u00e3o se mata a verdade matando jornalistas\u201d, que tratar\u00e1 do assassinato e desaparecimento de 126 comunicadores<\/a>\u00a0e funcion\u00e1rios de empresas de comunica\u00e7\u00e3o registrados desde 2000 no M\u00e9xico, segundo o Reporte \u00cdndigo.<\/p>\n<p>At\u00e9 hoje, apenas\u00a0<a href=\"https:\/\/knightcenter.utexas.edu\/pt-br\/blog\/00-10807-dos-67-assassinatos-de-jornalistas-registrados-no-mexico-desde-2006-so-um-foi-resolvid\" target=\"_blank\" rel=\"noopener\">um dos 67 casos de assassinato registrados no M\u00e9xico desde 2006 foi resolvido<\/a>.<\/p>\n<p>O livro ser\u00e1\u00a0<a href=\"http:\/\/www.goteo.org\/project\/no-se-mata-la-verdad-matando-periodistas\" target=\"_blank\" rel=\"noopener\">financiado por doa\u00e7\u00f5es p\u00fablicas por meio da internet<\/a>, o chamado \u201ccrowdsourcing\u201d, e o objetivo \u00e9 dividir o n\u00famero de exemplares entre os doadores e os assistentes da\u00a0<a href=\"http:\/\/www.fil.com.mx\/\" target=\"_blank\" rel=\"noopener\">Feira Internacional do Livro de Guadalajara<\/a>, em novembro. A organiza\u00e7\u00e3o Nossa Aparente Rendi\u00e7\u00e3o (NAR) tenta arrecadar mais de 16 mil d\u00f3lares para publicar o livro - e j\u00e1 conseguiu quase 6,8 mil.<\/p>\n<p>A NAR surgiu para criar uma p\u00e1gina em\u00a0<a href=\"http:\/\/72migrantes.com\/\" target=\"_blank\" rel=\"noopener\">homenagem aos 72 imigrantes das Am\u00e9ricas Central e do Sul assassinados no M\u00e9xico<\/a>\u00a0e cujos corpos foram localizados em agosto de 2010 em Tamaulipas. Agora, as\u00a0<a href=\"http:\/\/www.elcultural.es\/noticias\/LETRAS\/3444\/Lolita_Bosch-_Tenemos_miedo_pero_tenemos_mas_tristeza\" target=\"_blank\" rel=\"noopener\">hist\u00f3rias de jornalistas mexicanos assassinados ou desaparecidos<\/a>\u00a0incluem fotos, mat\u00e9rias que publicaram antes de morrer, amea\u00e7as recebidas e as inconsist\u00eancias nas investiga\u00e7\u00f5es, explicou a editora Lolita Bosch ao El Cultural.<\/p>\n<p>A organiza\u00e7\u00e3o Artigo 19 se negou a participar do projeto por conta de uma desacordo em rela\u00e7\u00e3o ao n\u00famero de\u00a0<a href=\"http:\/\/www.sinembargo.mx\/17-08-2012\/334889\" target=\"_blank\" rel=\"noopener\">126 jornalistas assassinados<\/a>, segundo o site Sin Embargo. A organiza\u00e7\u00e3o registra 72 casos de jornalistas assassinatos desde 2000 nos quais as evid\u00eancias parecem indicar que o crime foi cometido em repres\u00e1lia \u00e0 cobertura jornal\u00edstica. Nos demais casos, h\u00e1 apenas suspeita de que o motivo do crime tenha sido o trabalho das v\u00edtimas.<\/p>\n<p><em>Nota do editor: Essa hist\u00f3ria foi publicada originalmente no blog de jornalismo nas Am\u00e9ricas do Centro Knight, o predecessor do LatAm Journalism Review.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 200 pessoas trabalham no\u00a0livro \u201cN\u00e3o se mata a verdade matando jornalistas\u201d, que tratar\u00e1 do assassinato e desaparecimento de 126 comunicadores\u00a0e funcion\u00e1rios de empresas de comunica\u00e7\u00e3o registrados desde 2000 no M\u00e9xico, segundo o Reporte \u00cdndigo.<\/p>\n","protected":false},"author":40,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1221],"tags":[1534,1581,1394],"coauthors":[],"class_list":["post-31945","post","type-post","status-publish","format-standard","hentry","category-violencia-contra-jornalistas-pt-br","tag-ataques-contra-jornalistas-pt-br","tag-impunidade-pt-br","tag-mexico-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados - LatAm Journalism Review by the Knight Center<\/title>\n<meta name=\"description\" content=\"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados Viol\u00eancia contra jornalistas. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados\" \/>\n<meta property=\"og:description\" content=\"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados Viol\u00eancia contra jornalistas. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Journalism Review by the Knight Center\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-28T01:21:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-17T01:24:39+00:00\" \/>\n<meta name=\"author\" content=\"Tania Lara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LatAmJournalism\" \/>\n<meta name=\"twitter:site\" content=\"@LatAmJournalism\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tania Lara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/\"},\"author\":{\"name\":\"Tania Lara\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/51558925140f21242c6ed2d20b8260c5\"},\"headline\":\"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados\",\"datePublished\":\"2012-06-28T01:21:56+00:00\",\"dateModified\":\"2021-09-17T01:24:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\"},\"keywords\":[\"Ataques contra jornalistas\",\"Impunidade\",\"M\u00e9xico\"],\"articleSection\":[\"Viol\u00eancia contra jornalistas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/\",\"name\":\"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados - LatAm Journalism Review by the Knight Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#website\"},\"datePublished\":\"2012-06-28T01:21:56+00:00\",\"dateModified\":\"2021-09-17T01:24:39+00:00\",\"description\":\"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados Viol\u00eancia contra jornalistas. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\",\"name\":\"LatAm Journalism Review\",\"description\":\"Digital magazine on journalism in Latin America\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\",\"name\":\"LatAm Journalism Review\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"LatAm Journalism Review\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/LatAmJournalism\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/51558925140f21242c6ed2d20b8260c5\",\"name\":\"Tania Lara\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/author\\\/tania-lara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados - LatAm Journalism Review by the Knight Center","description":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados Viol\u00eancia contra jornalistas. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/","og_locale":"pt_BR","og_type":"article","og_title":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados","og_description":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados Viol\u00eancia contra jornalistas. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","og_url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/","og_site_name":"LatAm Journalism Review by the Knight Center","article_published_time":"2012-06-28T01:21:56+00:00","article_modified_time":"2021-09-17T01:24:39+00:00","author":"Tania Lara","twitter_card":"summary_large_image","twitter_creator":"@LatAmJournalism","twitter_site":"@LatAmJournalism","twitter_misc":{"Written by":"Tania Lara","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/#article","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/"},"author":{"name":"Tania Lara","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/person\/51558925140f21242c6ed2d20b8260c5"},"headline":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados","datePublished":"2012-06-28T01:21:56+00:00","dateModified":"2021-09-17T01:24:39+00:00","mainEntityOfPage":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/"},"wordCount":303,"publisher":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization"},"keywords":["Ataques contra jornalistas","Impunidade","M\u00e9xico"],"articleSection":["Viol\u00eancia contra jornalistas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/","url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/","name":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados - LatAm Journalism Review by the Knight Center","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#website"},"datePublished":"2012-06-28T01:21:56+00:00","dateModified":"2021-09-17T01:24:39+00:00","description":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados Viol\u00eancia contra jornalistas. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","breadcrumb":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/no-mexico-movimento-na-internet-pede-doacoes-para-livro-sobre-jornalistas-assassinados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamjournalismreview.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"No M\u00e9xico, movimento na internet pede doa\u00e7\u00f5es para livro sobre jornalistas assassinados"}]},{"@type":"WebSite","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#website","url":"https:\/\/latamjournalismreview.org\/pt-br\/","name":"LatAm Journalism Review","description":"Digital magazine on journalism in Latin America","publisher":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamjournalismreview.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization","name":"LatAm Journalism Review","url":"https:\/\/latamjournalismreview.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","width":"1024","height":"1024","caption":"LatAm Journalism Review"},"image":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/LatAmJournalism"]},{"@type":"Person","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/person\/51558925140f21242c6ed2d20b8260c5","name":"Tania Lara","url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/author\/tania-lara\/"}]}},"_links":{"self":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/31945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/comments?post=31945"}],"version-history":[{"count":1,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/31945\/revisions"}],"predecessor-version":[{"id":31947,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/31945\/revisions\/31947"}],"wp:attachment":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/media?parent=31945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/categories?post=31945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/tags?post=31945"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/coauthors?post=31945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}