{"id":36456,"date":"2013-01-09T20:41:47","date_gmt":"2013-01-10T01:41:47","guid":{"rendered":"https:\/\/latamjournalismreview.org\/?p=36456"},"modified":"2021-10-08T18:06:58","modified_gmt":"2021-10-08T23:06:58","slug":"com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade","status":"publish","type":"post","link":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/","title":{"rendered":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade"},"content":{"rendered":"<p><em>Por Isabela Fraga<\/em><\/p>\n<p>O presidente da Venezuela, Hugo Ch\u00e1vez, est\u00e1 internado num hospital cubano em tratamento de um c\u00e2ncer na regi\u00e3o p\u00e9lvica, mas parece bastante presente nas ruas e nas televis\u00f5es do pa\u00eds -- em camisetas, cartazes, fotos e, mais recentemente, em <a href=\"http:\/\/multimedia.vtv.gob.ve\/es\/#!\/videos\/noticia\/nacionales\/yo-soy-chavez-muestra-el-amor-al-presidente-hugo-chavez\" target=\"_blank\" rel=\"noopener\">v\u00eddeos com imagens de arquivo nos quais um Ch\u00e1vez saud\u00e1vel e forte<\/a> est\u00e1 \u00e0 frente de multid\u00f5es, fazendo pronunciamentos, cumprimentado eleitores e crian\u00e7as.<\/p>\n<p>Com cerca de sete minutos que ocupam grande parte da programa\u00e7\u00e3o da televis\u00e3o estatal VTV, os v\u00eddeos tamb\u00e9m exibem fotos de eleitores segurando cartazes com os dizeres \"Yo soy Ch\u00e1vez\" (\"Eu sou Ch\u00e1vez\") e parecem ter a inten\u00e7\u00e3o de <a href=\"http:\/\/www.nytimes.com\/2013\/01\/08\/world\/americas\/videos-of-chavez-promote-stability-during-illness.html?pagewanted=1&amp;_r=1&amp;ref=world&amp;\" target=\"_blank\" rel=\"noopener\">assegurar o povo venezuelano de que seu presidente ainda comanda o pa\u00eds<\/a> e preencher o vazio deixado por sua lideran\u00e7a <i>in vivo<\/i>, segundo uma an\u00e1lise do New York Times publicada na \u00faltima segunda-feira, 7 de setembro.<\/p>\n<p>Diz a mat\u00e9ria: \"Ao colocar a imagem [de Ch\u00e1vez] \u00e0 frente e ao centro, afirmam analistas, o governo pode fortalecer sua posi\u00e7\u00e3o como administrador de seu legado, mobilizar seus partid\u00e1rios para a guerra de interpreta\u00e7\u00e3o da Constitui\u00e7\u00e3o e construir um impulso para si nas elei\u00e7\u00f5es, caso Ch\u00e1vez morra ou sua sa\u00fade o impe\u00e7a de governar\". Para manter a imagem de estabilidade, o governo venezuelano tem aberto processos contra emissoras que n\u00e3o transmitem os comunicados oficiais ou que contradizem as mensagens oficiais, al\u00e9m de monitorar redes sociais, como o Twitter.<\/p>\n<p>Ch\u00e1vez est\u00e1 internado em Cuba desde 11 de dezembro, quando passou por uma cirurgia complicada contra o c\u00e2ncer, e est\u00e1 atualmente sob tratamento de uma grave infec\u00e7\u00e3o respirat\u00f3ria. Segundo o jornal El Nacional, as autoridades venezuelanas afirmam que o <a href=\"http:\/\/www.el-nacional.com\/politica\/Ministro-Jorge-Arreaza-Twiter-Chavez_3_110418958.html\" target=\"_blank\" rel=\"noopener\">estado do presidente \u00e9 est\u00e1vel<\/a>, mas na ter\u00e7a-feira, 9 de janeiro, o governo anunciou que o presidente -- reeleito nas \u00faltimas elei\u00e7\u00f5es de outubro -- n\u00e3o est\u00e1 em condi\u00e7\u00f5es de tomar posse, ent\u00e3o programada para a quinta-feira, 10 de janeiro. Ap\u00f3s questionamentos sobre a legalidade do adiamento, o presidente da Assembleia Nacional da Venezuela, Diosdado Cabello, afirmou que Ch\u00e1vez tem \"<a href=\"http:\/\/www.eluniversal.com\/nacional-y-politica\/salud-presidencial\/130108\/an-otorga-a-chavez-permiso-por-el-tiempo-que-necesite\" target=\"_blank\" rel=\"noopener\">todo o tempo que precisar para se recuperar<\/a> e voltar \u00e0 Venezuela\", informou o El Universal.<\/p>\n<p>Nos v\u00eddeos, que s\u00e3o transmitidos a curtos intervalos nas emissoras do pa\u00eds, apoiadores do presidente dizem frases como \"Ch\u00e1vez \u00e9 vida!\", em <a href=\"http:\/\/www.reuters.com\/article\/2012\/12\/18\/us-venezuela-chavez-image-idUSBRE8BH14420121218\" target=\"_blank\" rel=\"noopener\">n\u00edveis de adora\u00e7\u00e3o que a ag\u00eancia de not\u00edcias Reuters classificou como \"hagiogr\u00e1ficos\"<\/a>, antecipando principalmente as elei\u00e7\u00f5es regionais que acontecer\u00e3o no pr\u00f3ximo dezembro. A refer\u00eancia religiosa tamb\u00e9m foi feita por um professor de comunica\u00e7\u00e3o consultado pelo NYT, que afirmou haver na Venezuela \"um processo de convers\u00e3o de Ch\u00e1vez em um mito de ra\u00edzes religiosas\". J\u00e1 o analista pol\u00edtico J. J. Rend\u00f3n. tamb\u00e9m entrevistado pelo jornal, comparou a saga de Ch\u00e1vez contra o c\u00e2ncer a uma novela, cujas reviravoltas na trama mant\u00eam os espectadores ansiosos.<\/p>\n<p>Os rumores e elocubra\u00e7\u00f5es a respeito da sa\u00fade do l\u00edder venezuelano levaram o <a href=\"http:\/\/knightcenter.utexas.edu\/pt-br\/blog\/00-12424-governo-venezuelano-acusa-midia-internacional-de-promover-guerra-psicologica-em-torno-\" target=\"_blank\" rel=\"noopener\">governo a acusar a m\u00eddia internacional de promover uma \"guerra psicol\u00f3gica\"<\/a> sobre o assunto. Enquanto apoiadores e opositores do governo discutem sobre quem est\u00e1 mentindo, um <a href=\"http:\/\/eltiempo.com.ve\/venezuela\/situacion\/chavez-ausente-de-venezuela-sigue-presente-en-las-calles-del-pais\/75993\" target=\"_blank\" rel=\"noopener\">Ch\u00e1vez forte e sorridente ocupa cada vez mais as ruas<\/a> e as televis\u00f5es de Caracas, cercado por grupos de eleitores que rezam por sua melhora, noticiou o El Tiempo. \"<a href=\"http:\/\/eltiempo.com.ve\/venezuela\/situacion\/chavez-ausente-de-venezuela-sigue-presente-en-las-calles-del-pais\/75993\" target=\"_blank\" rel=\"noopener\">Ch\u00e1vez est\u00e1 \u00e0 venda em forma de camisetas, em bon\u00e9s junto com seus insepar\u00e1veis Fidel Castro<\/a>, Evo Morales ou o revolucion\u00e1rio Che Guevara, mas tamb\u00e9m \u00e9 m\u00fasica, com trechos de pe\u00e7as da \u00faltima campanha eleitoral\", descreve a reportagem.<\/p>\n<p><strong>Processos e press\u00e3o<\/strong><\/p>\n<p>A briga entre o governo venezuelano e a m\u00eddia -- nacional e internacional -- \u00e9 de longa data, e a maior reclama\u00e7\u00e3o das emissoras de TV do pa\u00eds \u00e9 a <a href=\"http:\/\/knightcenter.utexas.edu\/pt-br\/blog\/00-10887-tempo-de-transmissoes-presidenciais-em-radio-e-tv-sao-forma-de-censura-na-venezuela\" target=\"_blank\" rel=\"noopener\">obrigatoriedade de transmitir v\u00e1rios minutos discursos de membros do governo<\/a> sobre diversos temas. A resist\u00eancia de algumas emissoras a cumprir a norma fez com que o governo abrisse na sexta-feira, 4 de janeiro, tr\u00eas processos contra um canal de televis\u00e3o e duas r\u00e1dios que n\u00e3o transmitiram um comunicado do ministro de Comunica\u00e7\u00e3o e Informa\u00e7\u00e3o, Ernesto Villegas, sobre o estado de sa\u00fade de Ch\u00e1vez -- o mesmo que acusava a m\u00eddia de promover guerra psicol\u00f3gica, noticiou o El Comercio.<\/p>\n<p>A Comiss\u00e3o Nacional de Telecomunica\u00e7\u00f5es da Venezuela (Conatel) tamb\u00e9m instaurou nesta quarta-feira, 9 de janeiro, um <a href=\"http:\/\/www.lapatilla.com\/site\/2013\/01\/09\/conatel-le-abre-un-procedimiento-administrativo-a-globovision\/\" target=\"_blank\" rel=\"noopener\">novo processo contra a emissora Globovisi\u00f3n por transmitir quatro microinformativos sobre o artigo 231<\/a> da Constitui\u00e7\u00e3o do pa\u00eds -- que versa sobre o <a href=\"http:\/\/www.elmundo.com.ve\/noticias\/actualidad\/noticias\/%C2%BFque-dice-el-articulo-231-de-la-constitucion-.aspx\" target=\"_blank\" rel=\"noopener\">dia de posse do candidato a presidente eleito<\/a>, 10 de janeiro, informou o site La Patilla. Segundo o El Universal, o governo entendeu que os informativos \"<a href=\"http:\/\/www.eluniversal.com\/nacional-y-politica\/130109\/conatel-abre-tercer-procedimiento-administrativo-contra-globovision\" target=\"_blank\" rel=\"noopener\">incitam o \u00f3dio, ansiedade e a altera\u00e7\u00e3o da ordem p\u00fablica<\/a>\".<\/p>\n<p>Governo e a emissora t\u00eam um longo hist\u00f3rico de querelas. Em junho de 2012, a <a href=\"http:\/\/knightcenter.utexas.edu\/pt-br\/blog\/00-10610-venezuelana-globovision-paga-multa-de-quase-25-milhoes-bolivares-para-evitar-embargo\" target=\"_blank\" rel=\"noopener\">Globovisi\u00f3n foi obrigada a pagar uma multa de quase 25 milh\u00f5es de bol\u00edvares<\/a> referentes a uma multa pela cobertura dos conflitos numa penitenci\u00e1ria, ocorridos no final de 2011. Um m\u00eas depois, o governo decretou o <a href=\"http:\/\/knightcenter.utexas.edu\/pt-br\/blog\/00-10620-sip-wan-ifra-e-outras-organizacoes-condenam-stj-venezuelano-por-ordenar-embargo-da-emi\" target=\"_blank\" rel=\"noopener\">embargo de bens da emissora<\/a>, o que foi condenado por diversas organiza\u00e7\u00f5es como SIP, WAN-IFRA e Rep\u00f3rteres sem Fronteiras.<\/p>\n<p>As tentativas do governo de impedir a circula\u00e7\u00e3o de informa\u00e7\u00f5es, rumores e boatos sobre Ch\u00e1vez chegou tamb\u00e9m \u00e0s redes sociais. No domingo, 6 de janeiro, o Servi\u00e7o Nacional de Intelig\u00eancia Bolivariano (Sebin) <a href=\"http:\/\/www.clasesdeperiodismo.com\/2013\/01\/09\/allanan-casa-de-tuitero-que-difundio-rumor-sobre-la-salud-de-chavez\/\" target=\"_blank\" rel=\"noopener\">invadiu a casa de um cidad\u00e3o acusado de tuitar rumores<\/a> sobre a sa\u00fade do presidente, noticiou o site Clases de Periodismo. Federico Medina Ravel (<a href=\"http:\/\/twitter.com\/LucioQuincioC\" target=\"_blank\" rel=\"noopener\">@LucioQuincioC<\/a>), primo de um jornalista da emissora de oposi\u00e7\u00e3o Globovisi\u00f3n, havia postado no Twitter -- antes do an\u00fancio oficial do governo que foi feito na quarta-feira, 8 de janeiro -- que Ch\u00e1vez n\u00e3o se recuperaria a tempo da cerim\u00f4nia de posse, originalmente marcada para a quinta-feira, dia 10. Segundo o site The Verge, <a href=\"http:\/\/www.theverge.com\/2013\/1\/9\/3853590\/venezuelan-government-raids-home-over-hugo-chavez-twitter-rumors\" target=\"_blank\" rel=\"noopener\">agentes do servi\u00e7o de intelig\u00eancia confiscaram computadores<\/a> da casa de Ravel.<\/p>\n<p><em>Nota do editor: Essa hist\u00f3ria foi publicada originalmente no blog Jornalismo nas Am\u00e9ricas do Centro Knight, o predecessor do LatAm Journalism Review.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da Venezuela, Hugo Ch\u00e1vez, est\u00e1 internado num hospital cubano em tratamento de um c\u00e2ncer na regi\u00e3o p\u00e9lvica, mas parece bastante presente nas ruas e nas televis\u00f5es do pa\u00eds.<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1228],"tags":[1379,2051,1602,1562,1402],"coauthors":[],"class_list":["post-36456","post","type-post","status-publish","format-standard","hentry","category-acesso-a-informacao-pt-br","tag-casos-judiciais-pt-br","tag-liberdade-de-expressao-pt-br","tag-midia-publica-pt-br","tag-radio-e-tv-pt-br","tag-venezuela-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade - LatAm Journalism Review by the Knight Center<\/title>\n<meta name=\"description\" content=\"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade Acesso a informa\u00e7\u00e3o. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade\" \/>\n<meta property=\"og:description\" content=\"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade Acesso a informa\u00e7\u00e3o. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Journalism Review by the Knight Center\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-10T01:41:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-08T23:06:58+00:00\" \/>\n<meta name=\"author\" content=\"Knight Center\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LatAmJournalism\" \/>\n<meta name=\"twitter:site\" content=\"@LatAmJournalism\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Knight Center\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/\"},\"author\":{\"name\":\"Knight Center\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/6c325fd0fef0cd167424c683e6577e19\"},\"headline\":\"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade\",\"datePublished\":\"2013-01-10T01:41:47+00:00\",\"dateModified\":\"2021-10-08T23:06:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/\"},\"wordCount\":1083,\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\"},\"keywords\":[\"Casos judiciais\",\"Liberdade de express\u00e3o\",\"M\u00eddia p\u00fablica\",\"R\u00e1dio e TV\",\"Venezuela\"],\"articleSection\":[\"Acesso a informa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/\",\"name\":\"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade - LatAm Journalism Review by the Knight Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#website\"},\"datePublished\":\"2013-01-10T01:41:47+00:00\",\"dateModified\":\"2021-10-08T23:06:58+00:00\",\"description\":\"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade Acesso a informa\u00e7\u00e3o. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\",\"name\":\"LatAm Journalism Review\",\"description\":\"Digital magazine on journalism in Latin America\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\",\"name\":\"LatAm Journalism Review\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"LatAm Journalism Review\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/LatAmJournalism\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/6c325fd0fef0cd167424c683e6577e19\",\"name\":\"Knight Center\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/author\\\/knight-center\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade - LatAm Journalism Review by the Knight Center","description":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade Acesso a informa\u00e7\u00e3o. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade","og_description":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade Acesso a informa\u00e7\u00e3o. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","og_url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/","og_site_name":"LatAm Journalism Review by the Knight Center","article_published_time":"2013-01-10T01:41:47+00:00","article_modified_time":"2021-10-08T23:06:58+00:00","author":"Knight Center","twitter_card":"summary_large_image","twitter_creator":"@LatAmJournalism","twitter_site":"@LatAmJournalism","twitter_misc":{"Written by":"Knight Center","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/#article","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/"},"author":{"name":"Knight Center","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/person\/6c325fd0fef0cd167424c683e6577e19"},"headline":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade","datePublished":"2013-01-10T01:41:47+00:00","dateModified":"2021-10-08T23:06:58+00:00","mainEntityOfPage":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/"},"wordCount":1083,"publisher":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization"},"keywords":["Casos judiciais","Liberdade de express\u00e3o","M\u00eddia p\u00fablica","R\u00e1dio e TV","Venezuela"],"articleSection":["Acesso a informa\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/","url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/","name":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade - LatAm Journalism Review by the Knight Center","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#website"},"datePublished":"2013-01-10T01:41:47+00:00","dateModified":"2021-10-08T23:06:58+00:00","description":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade Acesso a informa\u00e7\u00e3o. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","breadcrumb":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/com-chavez-internado-governo-promove-videos-oficiais-e-pressiona-meios-de-comunicacao-para-transmitir-imagem-de-estabilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamjournalismreview.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Com Ch\u00e1vez internado, governo promove v\u00eddeos oficiais e pressiona meios de comunica\u00e7\u00e3o para transmitir imagem de estabilidade"}]},{"@type":"WebSite","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#website","url":"https:\/\/latamjournalismreview.org\/pt-br\/","name":"LatAm Journalism Review","description":"Digital magazine on journalism in Latin America","publisher":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamjournalismreview.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization","name":"LatAm Journalism Review","url":"https:\/\/latamjournalismreview.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","width":"1024","height":"1024","caption":"LatAm Journalism Review"},"image":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/LatAmJournalism"]},{"@type":"Person","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/person\/6c325fd0fef0cd167424c683e6577e19","name":"Knight Center","url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/author\/knight-center\/"}]}},"_links":{"self":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/36456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/comments?post=36456"}],"version-history":[{"count":1,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/36456\/revisions"}],"predecessor-version":[{"id":36457,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/36456\/revisions\/36457"}],"wp:attachment":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/media?parent=36456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/categories?post=36456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/tags?post=36456"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/coauthors?post=36456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}