{"id":85617,"date":"2024-03-21T16:27:34","date_gmt":"2024-03-21T21:27:34","guid":{"rendered":"https:\/\/latamjournalismreview.org\/?p=85617"},"modified":"2024-03-21T16:27:34","modified_gmt":"2024-03-21T21:27:34","slug":"o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas","status":"publish","type":"post","link":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/","title":{"rendered":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas"},"content":{"rendered":"<p>A ascens\u00e3o da intelig\u00eancia artificial e de outras novas tecnologias apresenta oportunidades e desafios para jornalistas e comunicadores durante as elei\u00e7\u00f5es. Como um n\u00famero recorde de pessoas em todo o mundo se prepara para ir \u00e0s urnas este ano, a necessidade de entender o impacto da tecnologia nos processos democr\u00e1ticos nunca foi t\u00e3o urgente.<\/p>\n<p>Para preparar as principais partes interessadas para este super ano de elei\u00e7\u00f5es, o Centro Knight para o Jornalismo nas Am\u00e9ricas, em colabora\u00e7\u00e3o com a Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura (UNESCO) e o Programa das Na\u00e7\u00f5es Unidas para o Desenvolvimento (PNUD), tem o prazer de anunciar o lan\u00e7amento de um curso online gratuito e multil\u00edngue destinado a compreender o papel da IA nas elei\u00e7\u00f5es.<\/p>\n<p>\u201c<strong>Liberdade de express\u00e3o, intelig\u00eancia artificial e elei\u00e7\u00f5es<\/strong>\u201d \u00e9 um curso online aberto e massivo (MOOC) que ser\u00e1 realizado <strong>de 2 a 30 de abril de 2024<\/strong> e est\u00e1 sendo oferecido simultaneamente em <a href=\"https:\/\/journalismcourses.org\/product\/%d8%ad%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%aa%d8%b9%d8%a8%d9%8a%d8%b1%d8%8c-%d9%88%d8%a7%d9%84%d8%b0%d9%83%d8%a7%d8%a1-%d8%a7%d9%84%d8%a7%d8%b5%d8%b7%d9%86%d8%a7%d8%b9%d9%8a-%d9%88%d8%a7%d9%84%d8%a7\/\">\u00e1rabe<\/a>, <a href=\"https:\/\/journalismcourses.org\/product\/freedom-of-expression-artificial-intelligence-elections\/\">ingl\u00eas<\/a>, <a href=\"https:\/\/journalismcourses.org\/product\/liberte-dexpression-intelligence-artificielle-et-elections\/\">franc\u00eas<\/a>, <a href=\"https:\/\/journalismcourses.org\/product\/liberdade-de-expressao-inteligencia-artificial-e-eleicoes\/\">portugu\u00eas<\/a> e <a href=\"https:\/\/journalismcourses.org\/product\/libertad-de-expresion-inteligencia-artificial-y-elecciones\/\">espanhol.<\/a><\/p>\n<p><a href=\"https:\/\/journalismcourses.org\/product\/liberdade-de-expressao-inteligencia-artificial-e-eleicoes\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-85618 size-large\" src=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_BANNER-1536x579-1-1024x386.png\" alt=\"Liberdade de express\u00e3o, intelig\u00eancia artificial e elei\u00e7\u00f5es\" width=\"1024\" height=\"386\" srcset=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_BANNER-1536x579-1-1024x386.png 1024w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_BANNER-1536x579-1-300x113.png 300w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_BANNER-1536x579-1-768x290.png 768w, https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_BANNER-1536x579-1.png 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>\u201cAo testemunharmos um ano hist\u00f3rico com o uso sem precedentes da IA generativa e de outras tecnologias digitais em um n\u00famero sem precedentes de elei\u00e7\u00f5es, este MOOC ressalta a necessidade cr\u00edtica de gerenciar as oportunidades e os riscos associados \u00e0 IA e seus efeitos nos processos democr\u00e1ticos, inclusive para o pleno exerc\u00edcio da liberdade de express\u00e3o\u201d, disse Sylvie Coudray, diretora da divis\u00e3o de Liberdade de Express\u00e3o, Desenvolvimento de M\u00eddia e Alfabetiza\u00e7\u00e3o em M\u00eddia e Informa\u00e7\u00e3o da UNESCO. \u201cAo cooperar com o PNUD e o Centro Knight, a UNESCO pretende equipar os participantes com ferramentas pr\u00e1ticas e ideias para salvaguardar a integridade dos processos eleitorais diante de cen\u00e1rios tecnol\u00f3gicos em evolu\u00e7\u00e3o\u201d.<\/p>\n<p>Durante este curso, os participantes explorar\u00e3o a influ\u00eancia da IA nas elei\u00e7\u00f5es, permitindo que eles identifiquem amea\u00e7as como desinforma\u00e7\u00e3o e discurso de \u00f3dio. O curso oferece habilidades pr\u00e1ticas importantes, como alfabetiza\u00e7\u00e3o midi\u00e1tica e uso de ferramentas de detec\u00e7\u00e3o de IA, al\u00e9m de aprofundar as considera\u00e7\u00f5es \u00e9ticas para elei\u00e7\u00f5es transparentes e confi\u00e1veis.<\/p>\n<p>O curso ser\u00e1 conduzido por <strong>Albertina Piterbarg,<\/strong> especialista eleitoral s\u00eanior e jornalista que trabalha na se\u00e7\u00e3o de Liberdade de Express\u00e3o e Seguran\u00e7a de Jornalistas da UNESCO. H\u00e1 mais de 20 anos, Piterbarg dedica sua experi\u00eancia \u00e0s \u00e1reas de comunica\u00e7\u00e3o, processos eleitorais e envolvimento das mulheres na pol\u00edtica em v\u00e1rias organiza\u00e7\u00f5es internacionais. Ela realizou miss\u00f5es em pa\u00edses como N\u00edger, Costa do Marfim, Tun\u00edsia, L\u00edbia, Timor Leste, Nova Caled\u00f4nia, M\u00e9xico, Bol\u00edvia, Col\u00f4mbia, Equador, Rep\u00fablica Dominicana e Venezuela, entre outros.<\/p>\n<p>Junto com ela est\u00e3o tr\u00eas instrutores t\u00e9cnicos:<\/p>\n<ul>\n<li><strong>Prateek Sibal<\/strong>, especialista em programas da UNESCO em Paris, lidera iniciativas globais de IA e transforma\u00e7\u00e3o digital. Ele representa a UNESCO na GlobalPolicy.AI, presta consultoria internacional e leciona governo digital na universidade internacional de pesquisa Sciences Po, em Paris.<\/li>\n<li><strong>Tatiana Monney<\/strong>, especialista eleitoral do PNUD, \u00e9 especialista em di\u00e1logo e preven\u00e7\u00e3o de conflitos. Com 20 anos de experi\u00eancia trabalhando com a ONU, o FDFA su\u00ed\u00e7o e a UE, ela atuou como consultora eleitoral s\u00eanior do Servi\u00e7o Europeu de A\u00e7\u00e3o Externa e facilitou processos de negocia\u00e7\u00e3o entre \u00f3rg\u00e3os de gest\u00e3o eleitoral e partidos pol\u00edticos em todo o mundo.<\/li>\n<li><strong>Osama Aljaber<\/strong>, especialista em democracia digital do PNUD em Nova York, aproveita a tecnologia e a IA para aprimorar os processos democr\u00e1ticos. Ele apoia institui\u00e7\u00f5es, a sociedade civil e a m\u00eddia na integridade das informa\u00e7\u00f5es e no apoio eleitoral, e estabeleceu redes que promovem a democracia e a participa\u00e7\u00e3o digital. Aljaber tem mestrado em Dados, Cultura e Sociedade pela Universidade de Westminster e \u00e9 bacharel em Sistemas de Informa\u00e7\u00e3o Computacional pela Universidade Hashemita.<\/li>\n<\/ul>\n<p>Instrutores assistentes dar\u00e3o suporte \u00e0 equipe nos cursos de <a href=\"https:\/\/journalismcourses.org\/product\/liberte-dexpression-intelligence-artificielle-et-elections\/\">franc\u00eas<\/a>, <a href=\"https:\/\/journalismcourses.org\/product\/liberdade-de-expressao-inteligencia-artificial-e-eleicoes\/\">portugu\u00eas<\/a>, <a href=\"https:\/\/journalismcourses.org\/product\/libertad-de-expresion-inteligencia-artificial-y-elecciones\/\">espanhol<\/a> e <a href=\"https:\/\/journalismcourses.org\/product\/%d8%ad%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%aa%d8%b9%d8%a8%d9%8a%d8%b1%d8%8c-%d9%88%d8%a7%d9%84%d8%b0%d9%83%d8%a7%d8%a1-%d8%a7%d9%84%d8%a7%d8%b5%d8%b7%d9%86%d8%a7%d8%b9%d9%8a-%d9%88%d8%a7%d9%84%d8%a7\/\">\u00e1rabe<\/a>. <strong>Julie Godignon<\/strong>, consultora especializada em assist\u00eancia e observa\u00e7\u00e3o eleitoral, dar\u00e1 assist\u00eancia em franc\u00eas. <strong>Lucas Novaes Ferreira<\/strong>, anteriormente especialista em comunica\u00e7\u00e3o da UNESCO, com foco em liberdade de express\u00e3o e prote\u00e7\u00e3o de jornalistas, dar\u00e1 assist\u00eancia em portugu\u00eas. <strong>Cristina Perez Claeys<\/strong>, consultora independente em avalia\u00e7\u00e3o pol\u00edtica e an\u00e1lise de processos eleitorais, ser\u00e1 a instrutora assistente em espanhol. Por fim, <strong>Anass Bendriff,<\/strong> especialista e instrutor em m\u00eddia e comunica\u00e7\u00e3o com mais de 18 anos de experi\u00eancia na \u00e1rea, dar\u00e1 assist\u00eancia em \u00e1rabe.<\/p>\n<p>Por meio de uma combina\u00e7\u00e3o de aulas em v\u00eddeo, leituras, discuss\u00f5es e question\u00e1rios, os participantes podem trabalhar com os materiais do curso em seu pr\u00f3prio ritmo, concluindo atividades e participando de discuss\u00f5es conforme suas agendas permitirem. Seja voc\u00ea um profissional eleitoral, jornalista, membro de uma organiza\u00e7\u00e3o da sociedade civil, estudante, educador ou simplesmente um cidad\u00e3o interessado, este curso incentiva pessoas de v\u00e1rias origens a colaborar para influenciar a trajet\u00f3ria da democracia na era digital.<\/p>\n<p>O material do curso est\u00e1 organizado em quatro m\u00f3dulos.<\/p>\n<ul>\n<li>O <em><strong>M\u00f3dulo 1<\/strong><\/em> apresenta aos participantes a interse\u00e7\u00e3o da IA e da liberdade de express\u00e3o em contextos eleitorais, explorando os padr\u00f5es internacionais e as implica\u00e7\u00f5es \u00e9ticas da IA.<\/li>\n<li>O <em><strong>M\u00f3dulo 2<\/strong><\/em> investiga os desafios da desinforma\u00e7\u00e3o, do discurso de \u00f3dio e da viol\u00eancia de g\u00eanero nas elei\u00e7\u00f5es, examinando o papel da IA e as estrat\u00e9gias de mitiga\u00e7\u00e3o.<\/li>\n<li>O <em><strong>M\u00f3dulo 3<\/strong><\/em> concentra-se em respostas colaborativas para combater o conte\u00fado nocivo gerado pela IA, enfatizando ferramentas e estrat\u00e9gias para v\u00e1rias partes interessadas.<\/li>\n<li>O <em><strong>M\u00f3dulo 4<\/strong><\/em> prepara os participantes com habilidades e ferramentas individuais para lidar com pr\u00e1ticas prejudiciais \u00e0 integridade das informa\u00e7\u00f5es durante as elei\u00e7\u00f5es, enfatizando considera\u00e7\u00f5es \u00e9ticas e estrat\u00e9gias pr\u00e1ticas.<\/li>\n<\/ul>\n<p>Ap\u00f3s a conclus\u00e3o bem-sucedida dos requisitos do curso, os participantes t\u00eam direito a um certificado de conclus\u00e3o gratuito. Nenhum cr\u00e9dito acad\u00eamico formal est\u00e1 associado ao certificado.<\/p>\n<p>\u201cEm uma era em que as tecnologias digitais e a IA est\u00e3o se tornando cada vez mais centrais para a arquitetura da sociedade, \u00e9 fundamental enfatizar a necessidade de garantir que elas defendam, em vez de enfraquecer, os direitos humanos\u201d, disse Sarah Lister, chefe de Governan\u00e7a do Bureau for Policy and Programme Support (BPPS) do PNUD. \u201cNesse contexto, esperamos que este curso sirva como um recurso oportuno, preparando os participantes para navegar pelas complexidades \u00fanicas do super ano eleitoral.\u201d<\/p>\n<p>\u201cO Centro Knight tem orgulho de oferecer este importante curso multil\u00edngue online e agradece \u00e0 UNESCO e ao PNUD por tornarem poss\u00edvel este projeto, que beneficiar\u00e1 jornalistas, comunicadores em geral e cidad\u00e3os interessados em todo o mundo durante este super ano eleitoral\u201d, disse o professor Rosental Alves, titular da C\u00e1tedra UNESCO de Comunica\u00e7\u00e3o da Universidade do Texas em Austin e diretor fundador do Centro Knight.<\/p>\n<p><a href=\"https:\/\/journalismcourses.org\/product\/freedom-of-expression-artificial-intelligence-elections\/\">Junte-se a n\u00f3s<\/a> neste curso empolgante para entender melhor o papel da tecnologia na democracia, na liberdade de express\u00e3o e na integridade eleitoral.<\/p>\n<p><a href=\"https:\/\/journalismcourses.org\/product\/freedom-of-expression-artificial-intelligence-elections\/\">Inscreva-se hoje<\/a> mesmo e fa\u00e7a parte da conversa sobre IA e elei\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ascens\u00e3o da intelig\u00eancia artificial e de outras novas tecnologias apresenta oportunidades e desafios para jornalistas e comunicadores durante as elei\u00e7\u00f5es. Como um n\u00famero recorde de pessoas em todo o mundo se prepara para ir \u00e0s urnas este ano, a necessidade de entender o impacto da tecnologia nos processos democr\u00e1ticos nunca foi t\u00e3o urgente. Para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":85621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1350],"tags":[1546,2051],"coauthors":[2749],"class_list":["post-85617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-journalism-courses-pt-br","tag-eleicoes-pt-br","tag-liberdade-de-expressao-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas - LatAm Journalism Review by the Knight Center<\/title>\n<meta name=\"description\" content=\"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas Journalism Courses. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas\" \/>\n<meta property=\"og:description\" content=\"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas Journalism Courses. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Journalism Review by the Knight Center\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T21:27:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_MINI-BANNER-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"507\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Teresa Mioli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TeresaMioli\" \/>\n<meta name=\"twitter:site\" content=\"@LatAmJournalism\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teresa Mioli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/\"},\"author\":{\"name\":\"Teresa Mioli\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/b83a4912f05c8178389e917d8d51de03\"},\"headline\":\"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas\",\"datePublished\":\"2024-03-21T21:27:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/\"},\"wordCount\":1236,\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/PT_MINI-BANNER-1.png\",\"keywords\":[\"Elei\u00e7\u00f5es\",\"Liberdade de express\u00e3o\"],\"articleSection\":[\"Journalism Courses\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/\",\"name\":\"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas - LatAm Journalism Review by the Knight Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/PT_MINI-BANNER-1.png\",\"datePublished\":\"2024-03-21T21:27:34+00:00\",\"description\":\"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas Journalism Courses. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/PT_MINI-BANNER-1.png\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/PT_MINI-BANNER-1.png\",\"width\":507,\"height\":340,\"caption\":\"Liberdade de express\u00e3o, intelig\u00eancia artificial e elei\u00e7\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\",\"name\":\"LatAm Journalism Review\",\"description\":\"Digital magazine on journalism in Latin America\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#organization\",\"name\":\"LatAm Journalism Review\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"contentUrl\":\"https:\\\/\\\/latamjournalismreview.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/knight-latAm-review-logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"LatAm Journalism Review\"},\"image\":{\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/LatAmJournalism\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/b83a4912f05c8178389e917d8d51de03\",\"name\":\"Teresa Mioli\",\"description\":\"Teresa Mioli is the editorial manager for the Knight Center for Journalism in the Americas. She is interested in press freedom, democratization, and investigative journalism in Latin America and is dedicated to increasing awareness about the importance of independent news media to the health of democracies. She produces journalistic work with the aim of helping people to make informed decisions about their lives and societies and wants to make sure other journalists are able to do the same. She has Bachelors' degrees in Journalism and Plan II Honors (Liberal Arts) and a Master's degree in Latin American Studies, all from the University of Texas at Austin. She started her journalistic career at The Beaumont Enterprise in Southeast Texas where she last worked as a breaking news reporter. ______ Teresa Mioli es la directora editorial del Centro Knight para el Periodismo en las Am\u00e9ricas. Es una periodista con inter\u00e9s en la libertad de prensa, la democratizaci\u00f3n y el periodismo investigativo en Am\u00e9rica Latina y est\u00e1 dedicada a crear mayor consciencia sobre la importancia de los medios noticiosos independientes para la salud de las democracias. El objetivo de su trabajo period\u00edstico es ayudar las personas para que tomen decisiones informadas sobre sus vidas y sus sociedades, y busca que otros periodistas tengan la posibilidad de hacer lo mismo. Teresa tiene una licenciatura en Periodismo y Artes liberales (Plan II Honors), y una maestr\u00eda en Estudios Latinoamericanos, todos de la Universidad de Texas en Austin. Empez\u00f3 su carrera en periodismo en The Beaumont Enterprise al sureste de Texas, en donde recientemente trabaj\u00f3 como reportera de noticias de \u00faltima hora. Anteriormente ella fue la editora de LatAm Journalism Review del Centro Knight. ______ Teresa Mioli \u00e9 gerente editorial do Centro Knight para o Jornalismo nas Am\u00e9ricas. Ela se interessa por liberdade de imprensa, democratiza\u00e7\u00e3o e jornalismo investigativo na Am\u00e9rica Latina e se dedica a aumentar a conscientiza\u00e7\u00e3o sobre a import\u00e2ncia da m\u00eddia independente para a sa\u00fade das democracias. Ela produz trabalhos jornal\u00edsticos com o objetivo de ajudar as pessoas a tomarem decis\u00f5es informadas sobre suas vidas e sociedades e deseja garantir que outros jornalistas possam fazer o mesmo. Ela tem bacharelado em jornalismo e artes liberais e um mestrado em Estudos Latino-Americanos, todos pela Universidade do Texas em Austin. Ela come\u00e7ou sua carreira jornal\u00edstica na The Beaumont Enterprise no sudeste do Texas, onde trabalhou pela \u00faltima vez como rep\u00f3rter de not\u00edcias de \u00faltima hora.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/TeresaMioli\"],\"url\":\"https:\\\/\\\/latamjournalismreview.org\\\/pt-br\\\/articles\\\/author\\\/teresa-mioli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas - LatAm Journalism Review by the Knight Center","description":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas Journalism Courses. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/","og_locale":"pt_BR","og_type":"article","og_title":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas","og_description":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas Journalism Courses. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","og_url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/","og_site_name":"LatAm Journalism Review by the Knight Center","article_published_time":"2024-03-21T21:27:34+00:00","og_image":[{"width":507,"height":340,"url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_MINI-BANNER-1.png","type":"image\/png"}],"author":"Teresa Mioli","twitter_card":"summary_large_image","twitter_creator":"@TeresaMioli","twitter_site":"@LatAmJournalism","twitter_misc":{"Written by":"Teresa Mioli","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/#article","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/"},"author":{"name":"Teresa Mioli","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/person\/b83a4912f05c8178389e917d8d51de03"},"headline":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas","datePublished":"2024-03-21T21:27:34+00:00","mainEntityOfPage":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/"},"wordCount":1236,"publisher":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_MINI-BANNER-1.png","keywords":["Elei\u00e7\u00f5es","Liberdade de express\u00e3o"],"articleSection":["Journalism Courses"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/","url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/","name":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas - LatAm Journalism Review by the Knight Center","isPartOf":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/#primaryimage"},"image":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_MINI-BANNER-1.png","datePublished":"2024-03-21T21:27:34+00:00","description":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas Journalism Courses. Latin American Journalism Review by The Knight Center at The University of Texas at Austin.","breadcrumb":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/#primaryimage","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_MINI-BANNER-1.png","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2024\/03\/PT_MINI-BANNER-1.png","width":507,"height":340,"caption":"Liberdade de express\u00e3o, intelig\u00eancia artificial e elei\u00e7\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/o-impacto-da-ia-nas-eleicoes-e-na-liberdade-de-expressao-inscreva-se-agora-em-novo-curso-online-gratuito-em-cinco-idiomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamjournalismreview.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"O impacto da IA nas elei\u00e7\u00f5es e na liberdade de express\u00e3o: Inscreva-se agora em novo curso online gratuito em cinco idiomas"}]},{"@type":"WebSite","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#website","url":"https:\/\/latamjournalismreview.org\/pt-br\/","name":"LatAm Journalism Review","description":"Digital magazine on journalism in Latin America","publisher":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamjournalismreview.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#organization","name":"LatAm Journalism Review","url":"https:\/\/latamjournalismreview.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","contentUrl":"https:\/\/latamjournalismreview.org\/wp-content\/uploads\/2020\/05\/knight-latAm-review-logo.svg","width":"1024","height":"1024","caption":"LatAm Journalism Review"},"image":{"@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/LatAmJournalism"]},{"@type":"Person","@id":"https:\/\/latamjournalismreview.org\/pt-br\/#\/schema\/person\/b83a4912f05c8178389e917d8d51de03","name":"Teresa Mioli","description":"Teresa Mioli is the editorial manager for the Knight Center for Journalism in the Americas. She is interested in press freedom, democratization, and investigative journalism in Latin America and is dedicated to increasing awareness about the importance of independent news media to the health of democracies. She produces journalistic work with the aim of helping people to make informed decisions about their lives and societies and wants to make sure other journalists are able to do the same. She has Bachelors' degrees in Journalism and Plan II Honors (Liberal Arts) and a Master's degree in Latin American Studies, all from the University of Texas at Austin. She started her journalistic career at The Beaumont Enterprise in Southeast Texas where she last worked as a breaking news reporter. ______ Teresa Mioli es la directora editorial del Centro Knight para el Periodismo en las Am\u00e9ricas. Es una periodista con inter\u00e9s en la libertad de prensa, la democratizaci\u00f3n y el periodismo investigativo en Am\u00e9rica Latina y est\u00e1 dedicada a crear mayor consciencia sobre la importancia de los medios noticiosos independientes para la salud de las democracias. El objetivo de su trabajo period\u00edstico es ayudar las personas para que tomen decisiones informadas sobre sus vidas y sus sociedades, y busca que otros periodistas tengan la posibilidad de hacer lo mismo. Teresa tiene una licenciatura en Periodismo y Artes liberales (Plan II Honors), y una maestr\u00eda en Estudios Latinoamericanos, todos de la Universidad de Texas en Austin. Empez\u00f3 su carrera en periodismo en The Beaumont Enterprise al sureste de Texas, en donde recientemente trabaj\u00f3 como reportera de noticias de \u00faltima hora. Anteriormente ella fue la editora de LatAm Journalism Review del Centro Knight. ______ Teresa Mioli \u00e9 gerente editorial do Centro Knight para o Jornalismo nas Am\u00e9ricas. Ela se interessa por liberdade de imprensa, democratiza\u00e7\u00e3o e jornalismo investigativo na Am\u00e9rica Latina e se dedica a aumentar a conscientiza\u00e7\u00e3o sobre a import\u00e2ncia da m\u00eddia independente para a sa\u00fade das democracias. Ela produz trabalhos jornal\u00edsticos com o objetivo de ajudar as pessoas a tomarem decis\u00f5es informadas sobre suas vidas e sociedades e deseja garantir que outros jornalistas possam fazer o mesmo. Ela tem bacharelado em jornalismo e artes liberais e um mestrado em Estudos Latino-Americanos, todos pela Universidade do Texas em Austin. Ela come\u00e7ou sua carreira jornal\u00edstica na The Beaumont Enterprise no sudeste do Texas, onde trabalhou pela \u00faltima vez como rep\u00f3rter de not\u00edcias de \u00faltima hora.","sameAs":["https:\/\/x.com\/TeresaMioli"],"url":"https:\/\/latamjournalismreview.org\/pt-br\/articles\/author\/teresa-mioli\/"}]}},"_links":{"self":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/85617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/comments?post=85617"}],"version-history":[{"count":1,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/85617\/revisions"}],"predecessor-version":[{"id":85624,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/posts\/85617\/revisions\/85624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/media\/85621"}],"wp:attachment":[{"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/media?parent=85617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/categories?post=85617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/tags?post=85617"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/latamjournalismreview.org\/pt-br\/wp-json\/wp\/v2\/coauthors?post=85617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}